{"id":387437,"date":"2025-11-12T13:13:40","date_gmt":"2025-11-12T12:13:40","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/?p=387437"},"modified":"2025-11-12T13:13:40","modified_gmt":"2025-11-12T12:13:40","slug":"finances-2026-la-tunisie-mise-sur-lautonomie-economique","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/","title":{"rendered":"Finances 2026 : La Tunisie mise sur l\u2019autonomie \u00e9conomique"},"content":{"rendered":"\n<p><em>Le rapport conjoint des commissions des finances de l\u2019Assembl\u00e9e des repr\u00e9sentants du peuple et du Conseil national des r\u00e9gions et des districts, pr\u00e9sent\u00e9 ce mercredi 12 novembre lors de la s\u00e9ance pl\u00e9ni\u00e8re consacr\u00e9e \u00e0 la mission du minist\u00e8re des Finances, dresse un tableau contrast\u00e9 mais globalement positif de la situation \u00e9conomique du pays \u00e0 l\u2019approche de 2026.<\/em><\/p>\n\n\n\n<p>Malgr\u00e9 la persistance des tensions g\u00e9opolitiques, notamment au Moyen-Orient, et les effets du changement climatique, la Tunisie est parvenue \u00e0 maintenir une relative stabilit\u00e9 budg\u00e9taire. Selon le rapport, l\u2019ann\u00e9e 2024 a enregistr\u00e9 des indicateurs positifs, avec un respect int\u00e9gral des engagements financiers internes et externes de l\u2019\u00c9tat et un financement assur\u00e9 principalement \u00e0 travers les ressources propres du pays.<\/p>\n\n\n\n<p>Ces ressources, estim\u00e9es \u00e0 47 011,5 millions de dinars, ont connu une hausse de 8,7 % par rapport \u00e0 2023 (5,5 %). Cette progression repose essentiellement sur les recettes fiscales, qui repr\u00e9sentent environ 89 % des revenus budg\u00e9taires, contribuant ainsi \u00e0 limiter le d\u00e9ficit de l\u2019\u00c9tat \u00e0 6,4 %, contre 7,6 % enregistr\u00e9s l\u2019ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n\n\n\n<p>En 2025, le gouvernement a poursuivi sa politique de consolidation des ressources propres, dans le cadre d\u2019une strat\u00e9gie de souverainet\u00e9 \u00e9conomique. Les efforts du minist\u00e8re des Finances ont permis, jusqu\u2019au mois d\u2019ao\u00fbt 2025, une progression de 5,6 % des recettes globales du budget par rapport \u00e0 la m\u00eame p\u00e9riode de 2024. Les recettes fiscales ont progress\u00e9 de 6,4 %, tandis que les recettes non fiscales ont augment\u00e9 de 12,2 %.<\/p>\n\n\n\n<p>Ces r\u00e9sultats traduisent une volont\u00e9 politique claire : renforcer l\u2019autonomie financi\u00e8re du pays et r\u00e9duire la d\u00e9pendance vis-\u00e0-vis de l\u2019endettement ext\u00e9rieur, tout en s\u2019inscrivant dans les orientations du plan de d\u00e9veloppement 2026-2030 actuellement en pr\u00e9paration. Ce plan vise \u00e0 consolider la souverainet\u00e9 nationale, \u00e0 pr\u00e9server l\u2019ind\u00e9pendance des d\u00e9cisions \u00e9conomiques et \u00e0 promouvoir une ouverture \u00e9quilibr\u00e9e sur le plan r\u00e9gional et international.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Lire aussi :\u00a0<a href=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-kais-saied-insiste-sur-la-justice-sociale-et-la-lutte-contre-la-corruption\/379238\/\">Tunisie : Kais Saied insiste sur la justice sociale et la lutte contre la corruption<\/a><\/p>\n<\/blockquote>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Le rapport conjoint des commissions des finances de l\u2019Assembl\u00e9e des repr\u00e9sentants du peuple et du Conseil national des r\u00e9gions et des districts, pr\u00e9sent\u00e9 ce mercredi 12 novembre lors de la s\u00e9ance pl\u00e9ni\u00e8re consacr\u00e9e \u00e0 la mission du minist\u00e8re des Finances, dresse un tableau contrast\u00e9 mais globalement positif de la situation \u00e9conomique du pays \u00e0 l\u2019approche [&hellip;]<\/p>\n","protected":false},"author":3184,"featured_media":378287,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[3642,2608],"class_list":["post-387437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-national","tag-finances","tag-tunisie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Finances 2026 : La Tunisie mise sur l\u2019autonomie \u00e9conomique - webdo<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les derni\u00e8res analyses sur les finances de la Tunisie et la stabilit\u00e9 \u00e9conomique \u00e0 l&#039;horizon 2026.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finances 2026 : La Tunisie mise sur l\u2019autonomie \u00e9conomique\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les derni\u00e8res analyses sur les finances de la Tunisie et la stabilit\u00e9 \u00e9conomique \u00e0 l&#039;horizon 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-12T12:13:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/M.-Finances-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wided Belhaj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wided Belhaj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/\"},\"author\":{\"name\":\"Wided Belhaj\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/b9ecde7a5574cb4fcf4b496ea5fadb15\"},\"headline\":\"Finances 2026 : La Tunisie mise sur l\u2019autonomie \u00e9conomique\",\"datePublished\":\"2025-11-12T12:13:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/\"},\"wordCount\":340,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/M.-Finances-1.jpg\",\"keywords\":[\"Finances\",\"Tunisie\"],\"articleSection\":[\"National\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/\",\"name\":\"Finances 2026 : La Tunisie mise sur l\u2019autonomie \u00e9conomique - webdo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/M.-Finances-1.jpg\",\"datePublished\":\"2025-11-12T12:13:40+00:00\",\"description\":\"D\u00e9couvrez les derni\u00e8res analyses sur les finances de la Tunisie et la stabilit\u00e9 \u00e9conomique \u00e0 l'horizon 2026.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/M.-Finances-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/M.-Finances-1.jpg\",\"width\":1280,\"height\":960,\"caption\":\"Tunisiens \u00e9tablis \u00e0 l\u2019\u00e9tranger : All\u00e8gement majeur des formalit\u00e9s fiscales en Tunisie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\\\/387437\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finances 2026 : La Tunisie mise sur l\u2019autonomie \u00e9conomique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/b9ecde7a5574cb4fcf4b496ea5fadb15\",\"name\":\"Wided Belhaj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"caption\":\"Wided Belhaj\"},\"description\":\"Wided Belhaj est le pseudonyme \u00e9ditorial utilis\u00e9 par Khalil Jelassi, journaliste, ma\u00eetre-assistant \u00e0 l\u2019Institut de presse et des sciences de l\u2019information (IPSI) et chercheur en sciences de l\u2019information et de la communication. Cette signature est d\u00e9di\u00e9e \u00e0 l\u2019analyse des m\u00e9dias, des pratiques journalistiques et des mutations de l\u2019information \u00e0 l\u2019\u00e8re digitale. \u00c0 travers ses contributions, Wided Belhaj propose une lecture analytique de l\u2019actualit\u00e9, en croisant regard critique et expertise acad\u00e9mique.\",\"knowsAbout\":[\"m\u00e9dias\",\"journalisme\",\"communication\",\"information\",\"transformation num\u00e9rique\",\"analyse des m\u00e9dias\"],\"knowsLanguage\":[\"Fran\u00e7ais\",\"Arabe\"],\"jobTitle\":\"Webdo.tn\",\"worksFor\":\"Journaliste \u2013 Analyse des m\u00e9dias\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/wided-belhaj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Finances 2026 : La Tunisie mise sur l\u2019autonomie \u00e9conomique - webdo","description":"D\u00e9couvrez les derni\u00e8res analyses sur les finances de la Tunisie et la stabilit\u00e9 \u00e9conomique \u00e0 l'horizon 2026.","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/","og_locale":"fr_FR","og_type":"article","og_title":"Finances 2026 : La Tunisie mise sur l\u2019autonomie \u00e9conomique","og_description":"D\u00e9couvrez les derni\u00e8res analyses sur les finances de la Tunisie et la stabilit\u00e9 \u00e9conomique \u00e0 l'horizon 2026.","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_published_time":"2025-11-12T12:13:40+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/M.-Finances-1.jpg","type":"image\/jpeg"}],"author":"Wided Belhaj","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"Wided Belhaj","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/"},"author":{"name":"Wided Belhaj","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/b9ecde7a5574cb4fcf4b496ea5fadb15"},"headline":"Finances 2026 : La Tunisie mise sur l\u2019autonomie \u00e9conomique","datePublished":"2025-11-12T12:13:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/"},"wordCount":340,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/M.-Finances-1.jpg","keywords":["Finances","Tunisie"],"articleSection":["National"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/","name":"Finances 2026 : La Tunisie mise sur l\u2019autonomie \u00e9conomique - webdo","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/M.-Finances-1.jpg","datePublished":"2025-11-12T12:13:40+00:00","description":"D\u00e9couvrez les derni\u00e8res analyses sur les finances de la Tunisie et la stabilit\u00e9 \u00e9conomique \u00e0 l'horizon 2026.","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/M.-Finances-1.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/M.-Finances-1.jpg","width":1280,"height":960,"caption":"Tunisiens \u00e9tablis \u00e0 l\u2019\u00e9tranger : All\u00e8gement majeur des formalit\u00e9s fiscales en Tunisie"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/finances-2026-la-tunisie-mise-sur-lautonomie-economique\/387437\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Finances 2026 : La Tunisie mise sur l\u2019autonomie \u00e9conomique"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/b9ecde7a5574cb4fcf4b496ea5fadb15","name":"Wided Belhaj","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","caption":"Wided Belhaj"},"description":"Wided Belhaj est le pseudonyme \u00e9ditorial utilis\u00e9 par Khalil Jelassi, journaliste, ma\u00eetre-assistant \u00e0 l\u2019Institut de presse et des sciences de l\u2019information (IPSI) et chercheur en sciences de l\u2019information et de la communication. Cette signature est d\u00e9di\u00e9e \u00e0 l\u2019analyse des m\u00e9dias, des pratiques journalistiques et des mutations de l\u2019information \u00e0 l\u2019\u00e8re digitale. \u00c0 travers ses contributions, Wided Belhaj propose une lecture analytique de l\u2019actualit\u00e9, en croisant regard critique et expertise acad\u00e9mique.","knowsAbout":["m\u00e9dias","journalisme","communication","information","transformation num\u00e9rique","analyse des m\u00e9dias"],"knowsLanguage":["Fran\u00e7ais","Arabe"],"jobTitle":"Webdo.tn","worksFor":"Journaliste \u2013 Analyse des m\u00e9dias","url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/wided-belhaj\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/387437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3184"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=387437"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/387437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/378287"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=387437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=387437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=387437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}