{"id":385847,"date":"2025-10-17T14:53:47","date_gmt":"2025-10-17T13:53:47","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/?p=385847"},"modified":"2025-10-17T14:54:39","modified_gmt":"2025-10-17T13:54:39","slug":"pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/","title":{"rendered":"Pluies abondantes et orages \u00e0 partir de ce soir : L\u2019INM lance une alerte"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Le temps conna\u00eetra un changement notable \u00e0 partir de la fin de l\u2019apr\u00e8s-midi de ce vendredi 17 octobre 2025. Selon un bulletin de suivi publi\u00e9 par l\u2019Institut National de la M\u00e9t\u00e9orologie (INM), des pluies parfois orageuses sont attendues sur les r\u00e9gions ouest du nord et du centre, avant de s\u2019\u00e9tendre dans la nuit au reste du nord. Ces pr\u00e9cipitations pourraient \u00eatre localement intenses, notamment dans l\u2019extr\u00eame nord.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-des-ce-soir\">D\u00e8s ce soir<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pluies orageuses sur le nord-ouest et le centre-ouest.<\/li>\n\n\n\n<li>Extension progressive vers les autres r\u00e9gions du nord durant la nuit.<\/li>\n\n\n\n<li>Pr\u00e9cipitations parfois fortes \u00e0 l\u2019extr\u00eame nord.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-samedi-des-pluies-sur-la-majorite-des-regions\">Samedi : des pluies sur la majorit\u00e9 des r\u00e9gions<\/h3>\n\n\n\n<p>L\u2019INM pr\u00e9voit des pr\u00e9cipitations sur la plupart des r\u00e9gions du pays, qui seront :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Localement orageuses et abondantes, d\u2019abord au sud-ouest.<\/li>\n\n\n\n<li>S\u2019\u00e9tendant dans l\u2019apr\u00e8s-midi vers le nord-ouest, le centre, puis localement le sud-est.<\/li>\n\n\n\n<li>Cumul attendu : entre 30 et 50 mm, pouvant atteindre 80 mm notamment sur le Sahel et Sfax.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-phenomenes-associes\">Ph\u00e9nom\u00e8nes associ\u00e9s<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Risque de chutes de gr\u00eale (gr\u00e9sil\/bard).<\/li>\n\n\n\n<li>Rafales de vent fortes, d\u00e9passant temporairement 70 km\/h lors des orages.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le temps conna\u00eetra un changement notable \u00e0 partir de la fin de l\u2019apr\u00e8s-midi de ce vendredi 17 octobre 2025. Selon un bulletin de suivi publi\u00e9 par l\u2019Institut National de la M\u00e9t\u00e9orologie (INM), des pluies parfois orageuses sont attendues sur les r\u00e9gions ouest du nord et du centre, avant de s\u2019\u00e9tendre dans la nuit au reste [&hellip;]<\/p>\n","protected":false},"author":3184,"featured_media":379303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[2670,2671,2608],"class_list":["post-385847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-national","tag-meteo","tag-pluie","tag-tunisie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pluies abondantes et orages \u00e0 partir de ce soir : L\u2019INM lance une alerte - webdo<\/title>\n<meta name=\"description\" content=\"Des pluies orageuses sont attendues ce vendredi, avec des intensit\u00e9s variables sur le nord, le nord-ouest et le centre-ouest.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pluies abondantes et orages \u00e0 partir de ce soir : L\u2019INM lance une alerte\" \/>\n<meta property=\"og:description\" content=\"Des pluies orageuses sont attendues ce vendredi, avec des intensit\u00e9s variables sur le nord, le nord-ouest et le centre-ouest.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-17T13:53:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T13:54:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/07\/meteopluiesorage-850x491-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"491\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wided Belhaj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wided Belhaj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/\"},\"author\":{\"name\":\"Wided Belhaj\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/b9ecde7a5574cb4fcf4b496ea5fadb15\"},\"headline\":\"Pluies abondantes et orages \u00e0 partir de ce soir : L\u2019INM lance une alerte\",\"datePublished\":\"2025-10-17T13:53:47+00:00\",\"dateModified\":\"2025-10-17T13:54:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/\"},\"wordCount\":209,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/meteopluiesorage-850x491-1.jpg\",\"keywords\":[\"m\u00e9t\u00e9o\",\"Pluie\",\"Tunisie\"],\"articleSection\":[\"National\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/\",\"name\":\"Pluies abondantes et orages \u00e0 partir de ce soir : L\u2019INM lance une alerte - webdo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/meteopluiesorage-850x491-1.jpg\",\"datePublished\":\"2025-10-17T13:53:47+00:00\",\"dateModified\":\"2025-10-17T13:54:39+00:00\",\"description\":\"Des pluies orageuses sont attendues ce vendredi, avec des intensit\u00e9s variables sur le nord, le nord-ouest et le centre-ouest.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/meteopluiesorage-850x491-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/meteopluiesorage-850x491-1.jpg\",\"width\":850,\"height\":491,\"caption\":\"orages localis\u00e9s \u00e0 l\u2019ouest et mer tr\u00e8s agit\u00e9e ce soir\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\\\/385847\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pluies abondantes et orages \u00e0 partir de ce soir : L\u2019INM lance une alerte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/b9ecde7a5574cb4fcf4b496ea5fadb15\",\"name\":\"Wided Belhaj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"caption\":\"Wided Belhaj\"},\"description\":\"Wided Belhaj est le pseudonyme \u00e9ditorial utilis\u00e9 par Khalil Jelassi, journaliste, ma\u00eetre-assistant \u00e0 l\u2019Institut de presse et des sciences de l\u2019information (IPSI) et chercheur en sciences de l\u2019information et de la communication. Cette signature est d\u00e9di\u00e9e \u00e0 l\u2019analyse des m\u00e9dias, des pratiques journalistiques et des mutations de l\u2019information \u00e0 l\u2019\u00e8re digitale. \u00c0 travers ses contributions, Wided Belhaj propose une lecture analytique de l\u2019actualit\u00e9, en croisant regard critique et expertise acad\u00e9mique.\",\"knowsAbout\":[\"m\u00e9dias\",\"journalisme\",\"communication\",\"information\",\"transformation num\u00e9rique\",\"analyse des m\u00e9dias\"],\"knowsLanguage\":[\"Fran\u00e7ais\",\"Arabe\"],\"jobTitle\":\"Webdo.tn\",\"worksFor\":\"Journaliste \u2013 Analyse des m\u00e9dias\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/wided-belhaj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pluies abondantes et orages \u00e0 partir de ce soir : L\u2019INM lance une alerte - webdo","description":"Des pluies orageuses sont attendues ce vendredi, avec des intensit\u00e9s variables sur le nord, le nord-ouest et le centre-ouest.","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/","og_locale":"fr_FR","og_type":"article","og_title":"Pluies abondantes et orages \u00e0 partir de ce soir : L\u2019INM lance une alerte","og_description":"Des pluies orageuses sont attendues ce vendredi, avec des intensit\u00e9s variables sur le nord, le nord-ouest et le centre-ouest.","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_published_time":"2025-10-17T13:53:47+00:00","article_modified_time":"2025-10-17T13:54:39+00:00","og_image":[{"width":850,"height":491,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/07\/meteopluiesorage-850x491-1.jpg","type":"image\/jpeg"}],"author":"Wided Belhaj","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"Wided Belhaj","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/"},"author":{"name":"Wided Belhaj","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/b9ecde7a5574cb4fcf4b496ea5fadb15"},"headline":"Pluies abondantes et orages \u00e0 partir de ce soir : L\u2019INM lance une alerte","datePublished":"2025-10-17T13:53:47+00:00","dateModified":"2025-10-17T13:54:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/"},"wordCount":209,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/07\/meteopluiesorage-850x491-1.jpg","keywords":["m\u00e9t\u00e9o","Pluie","Tunisie"],"articleSection":["National"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/","name":"Pluies abondantes et orages \u00e0 partir de ce soir : L\u2019INM lance une alerte - webdo","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/07\/meteopluiesorage-850x491-1.jpg","datePublished":"2025-10-17T13:53:47+00:00","dateModified":"2025-10-17T13:54:39+00:00","description":"Des pluies orageuses sont attendues ce vendredi, avec des intensit\u00e9s variables sur le nord, le nord-ouest et le centre-ouest.","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/07\/meteopluiesorage-850x491-1.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/07\/meteopluiesorage-850x491-1.jpg","width":850,"height":491,"caption":"orages localis\u00e9s \u00e0 l\u2019ouest et mer tr\u00e8s agit\u00e9e ce soir"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/pluies-abondantes-et-orages-a-partir-de-ce-soir-linm-lance-une-alerte\/385847\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Pluies abondantes et orages \u00e0 partir de ce soir : L\u2019INM lance une alerte"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/b9ecde7a5574cb4fcf4b496ea5fadb15","name":"Wided Belhaj","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","caption":"Wided Belhaj"},"description":"Wided Belhaj est le pseudonyme \u00e9ditorial utilis\u00e9 par Khalil Jelassi, journaliste, ma\u00eetre-assistant \u00e0 l\u2019Institut de presse et des sciences de l\u2019information (IPSI) et chercheur en sciences de l\u2019information et de la communication. Cette signature est d\u00e9di\u00e9e \u00e0 l\u2019analyse des m\u00e9dias, des pratiques journalistiques et des mutations de l\u2019information \u00e0 l\u2019\u00e8re digitale. \u00c0 travers ses contributions, Wided Belhaj propose une lecture analytique de l\u2019actualit\u00e9, en croisant regard critique et expertise acad\u00e9mique.","knowsAbout":["m\u00e9dias","journalisme","communication","information","transformation num\u00e9rique","analyse des m\u00e9dias"],"knowsLanguage":["Fran\u00e7ais","Arabe"],"jobTitle":"Webdo.tn","worksFor":"Journaliste \u2013 Analyse des m\u00e9dias","url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/wided-belhaj\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/385847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3184"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=385847"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/385847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/379303"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=385847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=385847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=385847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}