{"id":383072,"date":"2025-09-08T18:21:18","date_gmt":"2025-09-08T17:21:18","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/?p=383072"},"modified":"2025-09-08T18:21:18","modified_gmt":"2025-09-08T17:21:18","slug":"france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/","title":{"rendered":"France : Le gouvernement Bayrou renvers\u00e9 par un vote de d\u00e9fiance \u00e0 l\u2019Assembl\u00e9e"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Apr\u00e8s neuf mois seulement \u00e0 la t\u00eate du gouvernement, Fran\u00e7ois Bayrou a \u00e9t\u00e9 contraint de quitter Matignon. L\u2019Assembl\u00e9e nationale a adopt\u00e9 lundi une motion de d\u00e9fiance par <strong>364 voix contre 194<\/strong>, mettant un terme \u00e0 l\u2019exp\u00e9rience fragile de son gouvernement minoritaire.<\/p>\n\n\n\n<p>Ce revers, attendu mais retentissant, refl\u00e8te l\u2019ampleur de la crise politique que traverse la France. Nomm\u00e9 en d\u00e9cembre 2024 par Emmanuel Macron, Bayrou incarnait la tentative du pr\u00e9sident de trouver une figure de consensus au milieu d\u2019un paysage parlementaire \u00e9clat\u00e9. Mais son passage \u00e0 Matignon aura \u00e9t\u00e9 marqu\u00e9 par une impopulaire politique d\u2019aust\u00e9rit\u00e9 et une opposition persistante venue de tous les camps.<\/p>\n\n\n\n<p>Fran\u00e7ois Bayrou devient le <strong>troisi\u00e8me Premier ministre renvers\u00e9 en moins d\u2019un an<\/strong>, apr\u00e8s \u00c9lisabeth Borne et Gabriel Attal. Cette succession de crises gouvernementales traduit les difficult\u00e9s d\u2019Emmanuel Macron \u00e0 stabiliser une majorit\u00e9 et \u00e0 imposer son agenda dans une Assembl\u00e9e o\u00f9 aucun camp ne d\u00e9tient seul le pouvoir.<\/p>\n\n\n\n<p>Le pr\u00e9sident se retrouve d\u00e9sormais face \u00e0 un dilemme : tenter une nouvelle nomination \u2013 ce serait la <strong>quatri\u00e8me en moins de deux ans<\/strong> \u2013 ou convoquer des \u00e9lections anticip\u00e9es, au risque d\u2019ouvrir encore davantage l\u2019incertitude politique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-un-paysage-politique-fragmente\">Un paysage politique fragment\u00e9<\/h2>\n\n\n\n<p>Les oppositions, de la gauche \u00e0 l\u2019extr\u00eame droite, ont toutes salu\u00e9 la chute du gouvernement Bayrou comme une victoire contre ce qu\u2019elles d\u00e9noncent comme une gestion technocratique et d\u00e9connect\u00e9e. Mais elles ne parviennent pas pour autant \u00e0 dessiner une alternative claire et unifi\u00e9e.<\/p>\n\n\n\n<p>Dans ce climat de division et d\u2019instabilit\u00e9, la France entre dans une nouvelle phase d\u2019incertitude politique, o\u00f9 chaque d\u00e9cision pr\u00e9sidentielle pourrait reconfigurer en profondeur le paysage institutionnel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s neuf mois seulement \u00e0 la t\u00eate du gouvernement, Fran\u00e7ois Bayrou a \u00e9t\u00e9 contraint de quitter Matignon. L\u2019Assembl\u00e9e nationale a adopt\u00e9 lundi une motion de d\u00e9fiance par 364 voix contre 194, mettant un terme \u00e0 l\u2019exp\u00e9rience fragile de son gouvernement minoritaire. Ce revers, attendu mais retentissant, refl\u00e8te l\u2019ampleur de la crise politique que traverse la [&hellip;]<\/p>\n","protected":false},"author":3184,"featured_media":383073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2598],"tags":[2998,2651],"class_list":["post-383072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-international","tag-france","tag-gouvernement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>France : Le gouvernement Bayrou renvers\u00e9 par un vote de d\u00e9fiance \u00e0 l\u2019Assembl\u00e9e - webdo<\/title>\n<meta name=\"description\" content=\"Fran\u00e7ois Bayrou a quitt\u00e9 Matignon apr\u00e8s une motion de d\u00e9fiance. D\u00e9couvrez les d\u00e9tails de ce changement politique marquant.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"France : Le gouvernement Bayrou renvers\u00e9 par un vote de d\u00e9fiance \u00e0 l\u2019Assembl\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Fran\u00e7ois Bayrou a quitt\u00e9 Matignon apr\u00e8s une motion de d\u00e9fiance. D\u00e9couvrez les d\u00e9tails de ce changement politique marquant.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-08T17:21:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/09\/1779507-francois-bayrou.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wided Belhaj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wided Belhaj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/\"},\"author\":{\"name\":\"Wided Belhaj\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/b9ecde7a5574cb4fcf4b496ea5fadb15\"},\"headline\":\"France : Le gouvernement Bayrou renvers\u00e9 par un vote de d\u00e9fiance \u00e0 l\u2019Assembl\u00e9e\",\"datePublished\":\"2025-09-08T17:21:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/\"},\"wordCount\":302,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1779507-francois-bayrou.jpg\",\"keywords\":[\"france\",\"gouvernement\"],\"articleSection\":[\"International\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/\",\"name\":\"France : Le gouvernement Bayrou renvers\u00e9 par un vote de d\u00e9fiance \u00e0 l\u2019Assembl\u00e9e - webdo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1779507-francois-bayrou.jpg\",\"datePublished\":\"2025-09-08T17:21:18+00:00\",\"description\":\"Fran\u00e7ois Bayrou a quitt\u00e9 Matignon apr\u00e8s une motion de d\u00e9fiance. D\u00e9couvrez les d\u00e9tails de ce changement politique marquant.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1779507-francois-bayrou.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1779507-francois-bayrou.jpg\",\"width\":770,\"height\":513},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\\\/383072\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"France : Le gouvernement Bayrou renvers\u00e9 par un vote de d\u00e9fiance \u00e0 l\u2019Assembl\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/b9ecde7a5574cb4fcf4b496ea5fadb15\",\"name\":\"Wided Belhaj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"caption\":\"Wided Belhaj\"},\"description\":\"Wided Belhaj est le pseudonyme \u00e9ditorial utilis\u00e9 par Khalil Jelassi, journaliste, ma\u00eetre-assistant \u00e0 l\u2019Institut de presse et des sciences de l\u2019information (IPSI) et chercheur en sciences de l\u2019information et de la communication. Cette signature est d\u00e9di\u00e9e \u00e0 l\u2019analyse des m\u00e9dias, des pratiques journalistiques et des mutations de l\u2019information \u00e0 l\u2019\u00e8re digitale. \u00c0 travers ses contributions, Wided Belhaj propose une lecture analytique de l\u2019actualit\u00e9, en croisant regard critique et expertise acad\u00e9mique.\",\"knowsAbout\":[\"m\u00e9dias\",\"journalisme\",\"communication\",\"information\",\"transformation num\u00e9rique\",\"analyse des m\u00e9dias\"],\"knowsLanguage\":[\"Fran\u00e7ais\",\"Arabe\"],\"jobTitle\":\"Webdo.tn\",\"worksFor\":\"Journaliste \u2013 Analyse des m\u00e9dias\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/wided-belhaj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"France : Le gouvernement Bayrou renvers\u00e9 par un vote de d\u00e9fiance \u00e0 l\u2019Assembl\u00e9e - webdo","description":"Fran\u00e7ois Bayrou a quitt\u00e9 Matignon apr\u00e8s une motion de d\u00e9fiance. D\u00e9couvrez les d\u00e9tails de ce changement politique marquant.","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/","og_locale":"fr_FR","og_type":"article","og_title":"France : Le gouvernement Bayrou renvers\u00e9 par un vote de d\u00e9fiance \u00e0 l\u2019Assembl\u00e9e","og_description":"Fran\u00e7ois Bayrou a quitt\u00e9 Matignon apr\u00e8s une motion de d\u00e9fiance. D\u00e9couvrez les d\u00e9tails de ce changement politique marquant.","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_published_time":"2025-09-08T17:21:18+00:00","og_image":[{"width":770,"height":513,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/09\/1779507-francois-bayrou.jpg","type":"image\/jpeg"}],"author":"Wided Belhaj","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"Wided Belhaj","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/"},"author":{"name":"Wided Belhaj","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/b9ecde7a5574cb4fcf4b496ea5fadb15"},"headline":"France : Le gouvernement Bayrou renvers\u00e9 par un vote de d\u00e9fiance \u00e0 l\u2019Assembl\u00e9e","datePublished":"2025-09-08T17:21:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/"},"wordCount":302,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/09\/1779507-francois-bayrou.jpg","keywords":["france","gouvernement"],"articleSection":["International"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/","name":"France : Le gouvernement Bayrou renvers\u00e9 par un vote de d\u00e9fiance \u00e0 l\u2019Assembl\u00e9e - webdo","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/09\/1779507-francois-bayrou.jpg","datePublished":"2025-09-08T17:21:18+00:00","description":"Fran\u00e7ois Bayrou a quitt\u00e9 Matignon apr\u00e8s une motion de d\u00e9fiance. D\u00e9couvrez les d\u00e9tails de ce changement politique marquant.","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/09\/1779507-francois-bayrou.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/09\/1779507-francois-bayrou.jpg","width":770,"height":513},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/france-le-gouvernement-bayrou-renverse-par-un-vote-de-defiance-a-lassemblee\/383072\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"France : Le gouvernement Bayrou renvers\u00e9 par un vote de d\u00e9fiance \u00e0 l\u2019Assembl\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/b9ecde7a5574cb4fcf4b496ea5fadb15","name":"Wided Belhaj","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","caption":"Wided Belhaj"},"description":"Wided Belhaj est le pseudonyme \u00e9ditorial utilis\u00e9 par Khalil Jelassi, journaliste, ma\u00eetre-assistant \u00e0 l\u2019Institut de presse et des sciences de l\u2019information (IPSI) et chercheur en sciences de l\u2019information et de la communication. Cette signature est d\u00e9di\u00e9e \u00e0 l\u2019analyse des m\u00e9dias, des pratiques journalistiques et des mutations de l\u2019information \u00e0 l\u2019\u00e8re digitale. \u00c0 travers ses contributions, Wided Belhaj propose une lecture analytique de l\u2019actualit\u00e9, en croisant regard critique et expertise acad\u00e9mique.","knowsAbout":["m\u00e9dias","journalisme","communication","information","transformation num\u00e9rique","analyse des m\u00e9dias"],"knowsLanguage":["Fran\u00e7ais","Arabe"],"jobTitle":"Webdo.tn","worksFor":"Journaliste \u2013 Analyse des m\u00e9dias","url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/wided-belhaj\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/383072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3184"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=383072"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/383072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/383073"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=383072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=383072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=383072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}