{"id":381358,"date":"2025-08-12T08:05:12","date_gmt":"2025-08-12T07:05:12","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/?p=381358"},"modified":"2025-08-12T09:24:58","modified_gmt":"2025-08-12T08:24:58","slug":"legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/","title":{"rendered":"L\u2019Egypte n\u2019est pas contre le d\u00e9ploiement de forces internationales \u00e0 Gaza"},"content":{"rendered":"\n<p>Le Caire a r\u00e9it\u00e9r\u00e9, ce lundi, sa d\u00e9termination \u00e0 mettre fin \u00e0 l\u2019escalade \u00e0 Gaza et \u00e0 relancer un processus politique menant \u00e0 la cr\u00e9ation d\u2019un \u00c9tat palestinien. Lors d\u2019une conf\u00e9rence de presse conjointe avec son homologue ivoirien, le ministre \u00e9gyptien des Affaires \u00e9trang\u00e8res, Badr Abdelatty, a insist\u00e9 sur les priorit\u00e9s de son pays : <em>\u00ab Un cessez-le-feu imm\u00e9diat, l\u2019acheminement de l\u2019aide humanitaire, la lib\u00e9ration des otages et des prisonniers, et la pr\u00e9vention de toute extension des op\u00e9rations militaires et de l\u2019occupation isra\u00e9lienne \u00bb<\/em>.<\/p>\n\n\n\n<p>Abdelatty a rappel\u00e9 que l\u2019\u00c9gypte ne verrait aucun obstacle au d\u00e9ploiement de forces internationales, \u00e0 condition qu\u2019une feuille de route claire soit \u00e9tablie pour garantir la concr\u00e9tisation d\u2019un \u00c9tat palestinien dans un d\u00e9lai d\u00e9termin\u00e9.<\/p>\n\n\n\n<p>Le chef de la diplomatie \u00e9gyptienne a annonc\u00e9 l\u2019intention de son pays d\u2019organiser, d\u00e8s l\u2019instauration d\u2019un cessez-le-feu, une <strong>Conf\u00e9rence internationale pour la reconstruction de Gaza<\/strong>. Celle-ci viserait une relance rapide et durable de la bande c\u00f4ti\u00e8re, tout en posant les bases d\u2019un processus politique concret en faveur de la solution \u00e0 deux \u00c9tats.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-acheminement-d-une-aide-vitale-malgre-les-obstacles\">Acheminement d\u2019une aide vitale malgr\u00e9 les obstacles<\/h3>\n\n\n\n<p>Le ministre a affirm\u00e9 que l\u2019\u00c9gypte n\u2019avait jamais interrompu ses efforts, aussi bien sur le plan diplomatique que logistique, pour soutenir la population gazaouie. L\u2019aide humanitaire transite quotidiennement par le poste-fronti\u00e8re de Rafah, ouvert en permanence c\u00f4t\u00e9 \u00e9gyptien, ainsi que par celui de Karam Abu Salem.<\/p>\n\n\n\n<p>Cependant, Abdelatty a d\u00e9nonc\u00e9 les <strong>restrictions impos\u00e9es par Isra\u00ebl<\/strong> \u00e0 l\u2019entr\u00e9e de ces convois, compliquant l\u2019acheminement des vivres, m\u00e9dicaments et fournitures essentielles. Face \u00e0 cette situation, les forces arm\u00e9es \u00e9gyptiennes proc\u00e8dent \u00e9galement \u00e0 des <strong>largages a\u00e9riens<\/strong> afin de pallier les blocages et att\u00e9nuer la crise humanitaire.<\/p>\n\n\n\n<p>Ces d\u00e9clarations interviennent alors que de nouveaux convois franchissent Rafah pour rejoindre Gaza, poursuivant un effort que Le Caire affirme vouloir maintenir <em>\u00ab sans rel\u00e2che \u00bb<\/em> tant que la catastrophe humanitaire persiste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Caire a r\u00e9it\u00e9r\u00e9, ce lundi, sa d\u00e9termination \u00e0 mettre fin \u00e0 l\u2019escalade \u00e0 Gaza et \u00e0 relancer un processus politique menant \u00e0 la cr\u00e9ation d\u2019un \u00c9tat palestinien. Lors d\u2019une conf\u00e9rence de presse conjointe avec son homologue ivoirien, le ministre \u00e9gyptien des Affaires \u00e9trang\u00e8res, Badr Abdelatty, a insist\u00e9 sur les priorit\u00e9s de son pays : [&hellip;]<\/p>\n","protected":false},"author":3184,"featured_media":377687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2598],"tags":[3183,2689,2600],"class_list":["post-381358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-international","tag-egypte","tag-gaza","tag-guerre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L\u2019Egypte n\u2019est pas contre le d\u00e9ploiement de forces internationales \u00e0 Gaza - webdo<\/title>\n<meta name=\"description\" content=\"Le Caire s&#039;engage \u00e0 mettre fin \u00e0 l&#039;escalade \u00e0 Gaza et \u00e0 promouvoir la cr\u00e9ation d&#039;un \u00c9tat palestinien.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Egypte n\u2019est pas contre le d\u00e9ploiement de forces internationales \u00e0 Gaza\" \/>\n<meta property=\"og:description\" content=\"Le Caire s&#039;engage \u00e0 mettre fin \u00e0 l&#039;escalade \u00e0 Gaza et \u00e0 promouvoir la cr\u00e9ation d&#039;un \u00c9tat palestinien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-12T07:05:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T08:24:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Gaza-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wided Belhaj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wided Belhaj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/\"},\"author\":{\"name\":\"Wided Belhaj\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/b9ecde7a5574cb4fcf4b496ea5fadb15\"},\"headline\":\"L\u2019Egypte n\u2019est pas contre le d\u00e9ploiement de forces internationales \u00e0 Gaza\",\"datePublished\":\"2025-08-12T07:05:12+00:00\",\"dateModified\":\"2025-08-12T08:24:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Gaza-2.jpg\",\"keywords\":[\"Egypte\",\"Gaza\",\"guerre\"],\"articleSection\":[\"International\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/\",\"name\":\"L\u2019Egypte n\u2019est pas contre le d\u00e9ploiement de forces internationales \u00e0 Gaza - webdo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Gaza-2.jpg\",\"datePublished\":\"2025-08-12T07:05:12+00:00\",\"dateModified\":\"2025-08-12T08:24:58+00:00\",\"description\":\"Le Caire s'engage \u00e0 mettre fin \u00e0 l'escalade \u00e0 Gaza et \u00e0 promouvoir la cr\u00e9ation d'un \u00c9tat palestinien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Gaza-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Gaza-2.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\\\/381358\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Egypte n\u2019est pas contre le d\u00e9ploiement de forces internationales \u00e0 Gaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/b9ecde7a5574cb4fcf4b496ea5fadb15\",\"name\":\"Wided Belhaj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"caption\":\"Wided Belhaj\"},\"description\":\"Wided Belhaj est le pseudonyme \u00e9ditorial utilis\u00e9 par Khalil Jelassi, journaliste, ma\u00eetre-assistant \u00e0 l\u2019Institut de presse et des sciences de l\u2019information (IPSI) et chercheur en sciences de l\u2019information et de la communication. Cette signature est d\u00e9di\u00e9e \u00e0 l\u2019analyse des m\u00e9dias, des pratiques journalistiques et des mutations de l\u2019information \u00e0 l\u2019\u00e8re digitale. \u00c0 travers ses contributions, Wided Belhaj propose une lecture analytique de l\u2019actualit\u00e9, en croisant regard critique et expertise acad\u00e9mique.\",\"knowsAbout\":[\"m\u00e9dias\",\"journalisme\",\"communication\",\"information\",\"transformation num\u00e9rique\",\"analyse des m\u00e9dias\"],\"knowsLanguage\":[\"Fran\u00e7ais\",\"Arabe\"],\"jobTitle\":\"Webdo.tn\",\"worksFor\":\"Journaliste \u2013 Analyse des m\u00e9dias\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/wided-belhaj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L\u2019Egypte n\u2019est pas contre le d\u00e9ploiement de forces internationales \u00e0 Gaza - webdo","description":"Le Caire s'engage \u00e0 mettre fin \u00e0 l'escalade \u00e0 Gaza et \u00e0 promouvoir la cr\u00e9ation d'un \u00c9tat palestinien.","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019Egypte n\u2019est pas contre le d\u00e9ploiement de forces internationales \u00e0 Gaza","og_description":"Le Caire s'engage \u00e0 mettre fin \u00e0 l'escalade \u00e0 Gaza et \u00e0 promouvoir la cr\u00e9ation d'un \u00c9tat palestinien.","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_published_time":"2025-08-12T07:05:12+00:00","article_modified_time":"2025-08-12T08:24:58+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Gaza-2.jpg","type":"image\/jpeg"}],"author":"Wided Belhaj","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"Wided Belhaj","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/"},"author":{"name":"Wided Belhaj","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/b9ecde7a5574cb4fcf4b496ea5fadb15"},"headline":"L\u2019Egypte n\u2019est pas contre le d\u00e9ploiement de forces internationales \u00e0 Gaza","datePublished":"2025-08-12T07:05:12+00:00","dateModified":"2025-08-12T08:24:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Gaza-2.jpg","keywords":["Egypte","Gaza","guerre"],"articleSection":["International"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/","name":"L\u2019Egypte n\u2019est pas contre le d\u00e9ploiement de forces internationales \u00e0 Gaza - webdo","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Gaza-2.jpg","datePublished":"2025-08-12T07:05:12+00:00","dateModified":"2025-08-12T08:24:58+00:00","description":"Le Caire s'engage \u00e0 mettre fin \u00e0 l'escalade \u00e0 Gaza et \u00e0 promouvoir la cr\u00e9ation d'un \u00c9tat palestinien.","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Gaza-2.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Gaza-2.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/legypte-nest-pas-contre-le-deploiement-de-forces-internationales-a-gaza\/381358\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019Egypte n\u2019est pas contre le d\u00e9ploiement de forces internationales \u00e0 Gaza"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/b9ecde7a5574cb4fcf4b496ea5fadb15","name":"Wided Belhaj","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","caption":"Wided Belhaj"},"description":"Wided Belhaj est le pseudonyme \u00e9ditorial utilis\u00e9 par Khalil Jelassi, journaliste, ma\u00eetre-assistant \u00e0 l\u2019Institut de presse et des sciences de l\u2019information (IPSI) et chercheur en sciences de l\u2019information et de la communication. Cette signature est d\u00e9di\u00e9e \u00e0 l\u2019analyse des m\u00e9dias, des pratiques journalistiques et des mutations de l\u2019information \u00e0 l\u2019\u00e8re digitale. \u00c0 travers ses contributions, Wided Belhaj propose une lecture analytique de l\u2019actualit\u00e9, en croisant regard critique et expertise acad\u00e9mique.","knowsAbout":["m\u00e9dias","journalisme","communication","information","transformation num\u00e9rique","analyse des m\u00e9dias"],"knowsLanguage":["Fran\u00e7ais","Arabe"],"jobTitle":"Webdo.tn","worksFor":"Journaliste \u2013 Analyse des m\u00e9dias","url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/wided-belhaj\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/381358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3184"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=381358"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/381358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/377687"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=381358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=381358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=381358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}