{"id":381080,"date":"2025-08-07T08:15:47","date_gmt":"2025-08-07T07:15:47","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/?p=381080"},"modified":"2025-08-18T08:45:56","modified_gmt":"2025-08-18T07:45:56","slug":"tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/","title":{"rendered":"Tunisie : R\u00e9seaux en feu apr\u00e8s une bagarre sauvage entre deux rappeurs"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong>Une violente bagarre entre deux rappeurs tunisiens, Laya et Boussada, survenue hier \u00e0 l\u2019Ariana, a mis le feu aux r\u00e9seaux sociaux. Dans plusieurs vid\u00e9os virales, on peut voir les deux artistes se livrer \u00e0 une rixe brutale, encercl\u00e9s par une foule de spectateurs filmant la sc\u00e8ne avec leurs t\u00e9l\u00e9phones, visiblement plus fascin\u00e9s qu\u2019indign\u00e9s.<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/reel\/1460862478188660\">Ce face-\u00e0-face, organis\u00e9 comme un v\u00e9ritable \u00ab combat de rue \u00bb<\/a>, a choqu\u00e9 bon nombre d\u2019internautes par sa violence crue et sa mise en sc\u00e8ne presque ritualis\u00e9e. Les coups pleuvent, les cris fusent, et le tout est capt\u00e9, relay\u00e9 et comment\u00e9 \u00e0 grande vitesse sur TikTok, Instagram ou encore Facebook, o\u00f9 des centaines de jeunes fans suivent de pr\u00e8s ces figures de la sc\u00e8ne rap locale.<\/p>\n\n\n\n<p>Mais au-del\u00e0 du buzz, cet \u00e9pisode soul\u00e8ve des questions pr\u00e9occupantes sur la d\u00e9rive d&rsquo;une certaine culture urbaine en Tunisie. Car si le rap s\u2019est impos\u00e9 ces derni\u00e8res ann\u00e9es comme un moyen d\u2019expression artistique et sociale pour de nombreux jeunes, il semble d\u00e9sormais flirter dangereusement avec une glorification de la violence.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Cette culture underground, longtemps marginale, s\u2019installe d\u00e9sormais dans l\u2019espace public, aliment\u00e9e par des r\u00e9seaux sociaux avides de contenus spectaculaires et sensationnalistes. Ce n\u2019est plus uniquement une affaire de musique : c\u2019est tout un mode de vie, avec ses codes, ses provocations et parfois, ses d\u00e9rapages.<\/p>\n\n\n\n<p>\u00c0 l\u2019heure o\u00f9 la Tunisie est en qu\u00eate de rep\u00e8res pour sa jeunesse, certains craignent que ce genre d\u2019\u00e9pisodes ne contribue \u00e0 enraciner une culture de la violence et du clash comme nouvelle norme.<\/p>\n\n\n\n<p>Reste \u00e0 savoir si les autorit\u00e9s, comme les artistes eux-m\u00eames, sauront prendre la mesure de leur responsabilit\u00e9 dans la formation des imaginaires collectifs.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Lire aussi :<a href=\"https:\/\/www.webdo.tn\/fr\/actualite\/culture\/tunisie-un-premier-festival-international-dedie-au-rap-verra-le-jour\/379313\/\"> Tunisie : Un premier festival international d\u00e9di\u00e9 au rap verra le jour<\/a><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une violente bagarre entre deux rappeurs tunisiens, Laya et Boussada, survenue hier \u00e0 l\u2019Ariana, a mis le feu aux r\u00e9seaux sociaux. Dans plusieurs vid\u00e9os virales, on peut voir les deux artistes se livrer \u00e0 une rixe brutale, encercl\u00e9s par une foule de spectateurs filmant la sc\u00e8ne avec leurs t\u00e9l\u00e9phones, visiblement plus fascin\u00e9s qu\u2019indign\u00e9s. Ce face-\u00e0-face, [&hellip;]<\/p>\n","protected":false},"author":3184,"featured_media":381081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[6516,8830,4189,2608,2827],"class_list":["post-381080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-national","tag-bagarre","tag-rap","tag-rappeur","tag-tunisie","tag-violence"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tunisie : R\u00e9seaux en feu apr\u00e8s une bagarre sauvage entre deux rappeurs - webdo<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez l&#039;incident choquant entre les rappeurs Laya et Boussada qui a enflamm\u00e9 les r\u00e9seaux sociaux r\u00e9cemment.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tunisie : R\u00e9seaux en feu apr\u00e8s une bagarre sauvage entre deux rappeurs\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez l&#039;incident choquant entre les rappeurs Laya et Boussada qui a enflamm\u00e9 les r\u00e9seaux sociaux r\u00e9cemment.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-07T07:15:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-18T07:45:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-07-081347.png\" \/>\n\t<meta property=\"og:image:width\" content=\"815\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Wided Belhaj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wided Belhaj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/\"},\"author\":{\"name\":\"Wided Belhaj\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/b9ecde7a5574cb4fcf4b496ea5fadb15\"},\"headline\":\"Tunisie : R\u00e9seaux en feu apr\u00e8s une bagarre sauvage entre deux rappeurs\",\"datePublished\":\"2025-08-07T07:15:47+00:00\",\"dateModified\":\"2025-08-18T07:45:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/\"},\"wordCount\":329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Capture-decran-2025-08-07-081347.png\",\"keywords\":[\"bagarre\",\"rap\",\"Rappeur\",\"Tunisie\",\"violence\"],\"articleSection\":[\"National\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/\",\"name\":\"Tunisie : R\u00e9seaux en feu apr\u00e8s une bagarre sauvage entre deux rappeurs - webdo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Capture-decran-2025-08-07-081347.png\",\"datePublished\":\"2025-08-07T07:15:47+00:00\",\"dateModified\":\"2025-08-18T07:45:56+00:00\",\"description\":\"D\u00e9couvrez l'incident choquant entre les rappeurs Laya et Boussada qui a enflamm\u00e9 les r\u00e9seaux sociaux r\u00e9cemment.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Capture-decran-2025-08-07-081347.png\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Capture-decran-2025-08-07-081347.png\",\"width\":815,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\\\/381080\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tunisie : R\u00e9seaux en feu apr\u00e8s une bagarre sauvage entre deux rappeurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/b9ecde7a5574cb4fcf4b496ea5fadb15\",\"name\":\"Wided Belhaj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/wided-belhaj_avatar-96x96.jpg\",\"caption\":\"Wided Belhaj\"},\"description\":\"Wided Belhaj est le pseudonyme \u00e9ditorial utilis\u00e9 par Khalil Jelassi, journaliste, ma\u00eetre-assistant \u00e0 l\u2019Institut de presse et des sciences de l\u2019information (IPSI) et chercheur en sciences de l\u2019information et de la communication. Cette signature est d\u00e9di\u00e9e \u00e0 l\u2019analyse des m\u00e9dias, des pratiques journalistiques et des mutations de l\u2019information \u00e0 l\u2019\u00e8re digitale. \u00c0 travers ses contributions, Wided Belhaj propose une lecture analytique de l\u2019actualit\u00e9, en croisant regard critique et expertise acad\u00e9mique.\",\"knowsAbout\":[\"m\u00e9dias\",\"journalisme\",\"communication\",\"information\",\"transformation num\u00e9rique\",\"analyse des m\u00e9dias\"],\"knowsLanguage\":[\"Fran\u00e7ais\",\"Arabe\"],\"jobTitle\":\"Webdo.tn\",\"worksFor\":\"Journaliste \u2013 Analyse des m\u00e9dias\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/wided-belhaj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tunisie : R\u00e9seaux en feu apr\u00e8s une bagarre sauvage entre deux rappeurs - webdo","description":"D\u00e9couvrez l'incident choquant entre les rappeurs Laya et Boussada qui a enflamm\u00e9 les r\u00e9seaux sociaux r\u00e9cemment.","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/","og_locale":"fr_FR","og_type":"article","og_title":"Tunisie : R\u00e9seaux en feu apr\u00e8s une bagarre sauvage entre deux rappeurs","og_description":"D\u00e9couvrez l'incident choquant entre les rappeurs Laya et Boussada qui a enflamm\u00e9 les r\u00e9seaux sociaux r\u00e9cemment.","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_published_time":"2025-08-07T07:15:47+00:00","article_modified_time":"2025-08-18T07:45:56+00:00","og_image":[{"width":815,"height":531,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-07-081347.png","type":"image\/png"}],"author":"Wided Belhaj","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"Wided Belhaj","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/"},"author":{"name":"Wided Belhaj","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/b9ecde7a5574cb4fcf4b496ea5fadb15"},"headline":"Tunisie : R\u00e9seaux en feu apr\u00e8s une bagarre sauvage entre deux rappeurs","datePublished":"2025-08-07T07:15:47+00:00","dateModified":"2025-08-18T07:45:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/"},"wordCount":329,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-07-081347.png","keywords":["bagarre","rap","Rappeur","Tunisie","violence"],"articleSection":["National"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/","name":"Tunisie : R\u00e9seaux en feu apr\u00e8s une bagarre sauvage entre deux rappeurs - webdo","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-07-081347.png","datePublished":"2025-08-07T07:15:47+00:00","dateModified":"2025-08-18T07:45:56+00:00","description":"D\u00e9couvrez l'incident choquant entre les rappeurs Laya et Boussada qui a enflamm\u00e9 les r\u00e9seaux sociaux r\u00e9cemment.","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-07-081347.png","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/08\/Capture-decran-2025-08-07-081347.png","width":815,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-reseaux-en-feu-apres-une-bagarre-sauvage-entre-deux-rappeurs\/381080\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Tunisie : R\u00e9seaux en feu apr\u00e8s une bagarre sauvage entre deux rappeurs"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/b9ecde7a5574cb4fcf4b496ea5fadb15","name":"Wided Belhaj","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/wided-belhaj_avatar-96x96.jpg","caption":"Wided Belhaj"},"description":"Wided Belhaj est le pseudonyme \u00e9ditorial utilis\u00e9 par Khalil Jelassi, journaliste, ma\u00eetre-assistant \u00e0 l\u2019Institut de presse et des sciences de l\u2019information (IPSI) et chercheur en sciences de l\u2019information et de la communication. Cette signature est d\u00e9di\u00e9e \u00e0 l\u2019analyse des m\u00e9dias, des pratiques journalistiques et des mutations de l\u2019information \u00e0 l\u2019\u00e8re digitale. \u00c0 travers ses contributions, Wided Belhaj propose une lecture analytique de l\u2019actualit\u00e9, en croisant regard critique et expertise acad\u00e9mique.","knowsAbout":["m\u00e9dias","journalisme","communication","information","transformation num\u00e9rique","analyse des m\u00e9dias"],"knowsLanguage":["Fran\u00e7ais","Arabe"],"jobTitle":"Webdo.tn","worksFor":"Journaliste \u2013 Analyse des m\u00e9dias","url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/wided-belhaj\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/381080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3184"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=381080"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/381080\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/381081"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=381080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=381080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=381080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}