{"id":219712,"date":"2025-02-10T10:15:00","date_gmt":"2025-02-10T10:15:00","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/blog\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/"},"modified":"2025-05-20T22:16:35","modified_gmt":"2025-05-20T22:16:35","slug":"tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/","title":{"rendered":"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi"},"content":{"rendered":"<p>Depuis le 2 f\u00e9vrier 2025, un nouveau mod\u00e8le de ch\u00e8que est en circulation en Tunisie, marquant une \u00e9tape importante dans la modernisation des transactions bancaires. Cette r\u00e9forme vise \u00e0 renforcer la s\u00e9curit\u00e9 des op\u00e9rations financi\u00e8res et \u00e0 assurer une meilleure tra\u00e7abilit\u00e9 des paiements.<\/p>\n<p>\tLe nouveau mod\u00e8le de ch\u00e8que comporte plusieurs \u00e9l\u00e9ments essentiels :<br \/>\n\tLes noms du d\u00e9positaire et du b\u00e9n\u00e9ficiaire : Ils doivent \u00eatre mentionn\u00e9s clairement et sans rature.<br \/>\n\tLe montant en chiffres et en lettres : Une incoh\u00e9rence entre les deux pourrait entra\u00eener des litiges.<br \/>\n\tLa date et le lieu d&rsquo;\u00e9mission : Ils doivent \u00eatre pr\u00e9cis\u00e9s avec exactitude.<br \/>\n\tLe num\u00e9ro de compte et le nom de la banque : Ces informations assurent la bonne identification du compte.<br \/>\n\tLa signature du titulaire du compte : Elle doit correspondre \u00e0 celle enregistr\u00e9e \u00e0 la banque.<br \/>\n\tLe QR code : Une nouveaut\u00e9 int\u00e9gr\u00e9e permettant une v\u00e9rification num\u00e9rique.<\/p>\n<p>En outre, la validit\u00e9 du ch\u00e8que est limit\u00e9e \u00e0 six mois et son montant est plafonn\u00e9 \u00e0 30.000 dinars.<\/p>\n<p>Avec cette r\u00e9forme, une nouvelle plateforme \u00e9lectronique baptis\u00e9e \u00ab\u00a0Tunich\u00e8que\u00a0\u00bb a \u00e9t\u00e9 lanc\u00e9e pour offrir une meilleure transparence dans l\u2019utilisation des ch\u00e8ques.<\/p>\n<p>Cette plateforme permet aux \u00e9metteurs de ch\u00e8ques de consulter les informations relatives \u00e0 leurs comptes, et aux b\u00e9n\u00e9ficiaires de v\u00e9rifier la disponibilit\u00e9 des fonds avant d\u2019accepter un paiement. En scannant le QR code pr\u00e9sent sur le ch\u00e8que, le b\u00e9n\u00e9ficiaire peut s&rsquo;assurer que le montant est bien disponible sur le compte de l\u2019\u00e9metteur.<\/p>\n<p>Un autre avantage de \u00ab\u00a0Tunich\u00e8que\u00a0\u00bb est la possibilit\u00e9 de bloquer temporairement le montant sur le compte de l&rsquo;\u00e9metteur jusqu&rsquo;\u00e0 la pr\u00e9sentation du ch\u00e8que, garantissant ainsi une plus grande s\u00e9curit\u00e9 des transactions.<\/p>\n<p>Enfin, une fois le ch\u00e8que \u00e9mis, la plateforme envoie un avis de confirmation \u00e0 l\u2019utilisateur, validant l&rsquo;op\u00e9ration et confirmant la disponibilit\u00e9 des fonds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le 2 f\u00e9vrier 2025, un nouveau mod\u00e8le de ch\u00e8que est en circulation en Tunisie, marquant une \u00e9tape importante dans la modernisation des transactions bancaires. Cette r\u00e9forme vise \u00e0 renforcer la s\u00e9curit\u00e9 des op\u00e9rations financi\u00e8res et \u00e0 assurer une meilleure tra\u00e7abilit\u00e9 des paiements. Le nouveau mod\u00e8le de ch\u00e8que comporte plusieurs \u00e9l\u00e9ments essentiels : Les noms [&hellip;]<\/p>\n","protected":false},"author":3162,"featured_media":291871,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[10955,4159,3606,2608],"class_list":["post-219712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-national","tag-qr-code","tag-cheque","tag-tunicheque","tag-tunisie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi<\/title>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi\" \/>\n<meta property=\"og:description\" content=\"Depuis le 2 f\u00e9vrier 2025, un nouveau mod\u00e8le de ch\u00e8que est en circulation en Tunisie, marquant une \u00e9tape importante dans la modernisation des transactions bancaires. Cette r\u00e9forme vise \u00e0 renforcer la s\u00e9curit\u00e9 des op\u00e9rations financi\u00e8res et \u00e0 assurer une meilleure tra\u00e7abilit\u00e9 des paiements. Le nouveau mod\u00e8le de ch\u00e8que comporte plusieurs \u00e9l\u00e9ments essentiels : Les noms [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-10T10:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T22:16:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/02\/aa1dd1bed0c33df599acd05c77005c6d.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"MC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"MC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/\"},\"author\":{\"name\":\"MC\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/2c4929cbf5a809e3bd38617c6ce150f6\"},\"headline\":\"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi\",\"datePublished\":\"2025-02-10T10:15:00+00:00\",\"dateModified\":\"2025-05-20T22:16:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/\"},\"wordCount\":340,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/aa1dd1bed0c33df599acd05c77005c6d.webp\",\"keywords\":[\"'QR Code']\",\"ch\u00e9que\",\"tunich\u00e8que\",\"Tunisie\"],\"articleSection\":[\"National\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/\",\"name\":\"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/aa1dd1bed0c33df599acd05c77005c6d.webp\",\"datePublished\":\"2025-02-10T10:15:00+00:00\",\"dateModified\":\"2025-05-20T22:16:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/aa1dd1bed0c33df599acd05c77005c6d.webp\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/aa1dd1bed0c33df599acd05c77005c6d.webp\",\"width\":750,\"height\":400,\"caption\":\"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\\\/219712\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/2c4929cbf5a809e3bd38617c6ce150f6\",\"name\":\"MC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a545bbb6f84efdd5553dbbc2895e3ca8f1d12c5215e00a041c9670b54aa9b18a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a545bbb6f84efdd5553dbbc2895e3ca8f1d12c5215e00a041c9670b54aa9b18a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a545bbb6f84efdd5553dbbc2895e3ca8f1d12c5215e00a041c9670b54aa9b18a?s=96&d=mm&r=g\",\"caption\":\"MC\"},\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/mc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/","og_locale":"fr_FR","og_type":"article","og_title":"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi","og_description":"Depuis le 2 f\u00e9vrier 2025, un nouveau mod\u00e8le de ch\u00e8que est en circulation en Tunisie, marquant une \u00e9tape importante dans la modernisation des transactions bancaires. Cette r\u00e9forme vise \u00e0 renforcer la s\u00e9curit\u00e9 des op\u00e9rations financi\u00e8res et \u00e0 assurer une meilleure tra\u00e7abilit\u00e9 des paiements. Le nouveau mod\u00e8le de ch\u00e8que comporte plusieurs \u00e9l\u00e9ments essentiels : Les noms [&hellip;]","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_published_time":"2025-02-10T10:15:00+00:00","article_modified_time":"2025-05-20T22:16:35+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/02\/aa1dd1bed0c33df599acd05c77005c6d.webp","type":"image\/webp"}],"author":"MC","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"MC","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/"},"author":{"name":"MC","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/2c4929cbf5a809e3bd38617c6ce150f6"},"headline":"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi","datePublished":"2025-02-10T10:15:00+00:00","dateModified":"2025-05-20T22:16:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/"},"wordCount":340,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/02\/aa1dd1bed0c33df599acd05c77005c6d.webp","keywords":["'QR Code']","ch\u00e9que","tunich\u00e8que","Tunisie"],"articleSection":["National"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/","name":"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/02\/aa1dd1bed0c33df599acd05c77005c6d.webp","datePublished":"2025-02-10T10:15:00+00:00","dateModified":"2025-05-20T22:16:35+00:00","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/02\/aa1dd1bed0c33df599acd05c77005c6d.webp","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/02\/aa1dd1bed0c33df599acd05c77005c6d.webp","width":750,"height":400,"caption":"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/tunisie-tout-savoir-sur-le-nouveau-cheque-et-son-mode-d-emploi\/219712\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Tunisie : Tout savoir sur le nouveau ch\u00e8que et son mode d\u2019emploi"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/2c4929cbf5a809e3bd38617c6ce150f6","name":"MC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a545bbb6f84efdd5553dbbc2895e3ca8f1d12c5215e00a041c9670b54aa9b18a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a545bbb6f84efdd5553dbbc2895e3ca8f1d12c5215e00a041c9670b54aa9b18a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a545bbb6f84efdd5553dbbc2895e3ca8f1d12c5215e00a041c9670b54aa9b18a?s=96&d=mm&r=g","caption":"MC"},"url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/mc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/219712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3162"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=219712"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/219712\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/291871"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=219712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=219712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=219712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}