{"id":212079,"date":"2024-02-06T10:34:00","date_gmt":"2024-02-06T10:34:00","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/blog\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/"},"modified":"2024-02-06T10:34:00","modified_gmt":"2024-02-06T10:34:00","slug":"un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/","title":{"rendered":"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e"},"content":{"rendered":"<p>Le square Louis Wiriot se trouve au bout du quartier de la Petite Sicile et se caract\u00e9rise par un \u00e9difice abandonn\u00e9 et un \u00e9tat d\u00e9solant.<\/p>\n<p>\t\t\t\t\t\t\t\t\tMais qui donc \u00e9tait Louis Wiriot ? Si l&rsquo;histoire a retenu le nom de ce grand entrepreneur, la Tunisie l&rsquo;a compl\u00e8tement oubli\u00e9. Un square lui est d\u00e9di\u00e9 mais il reste un illustre inconnu.<\/p>\n<p>Louis Wiriot (1857-1928) a \u00e9t\u00e9 au d\u00e9but du vingti\u00e8me si\u00e8cle, le directeur des travaux de construction des ports de Tunis, Sousse et Sfax. Il a \u00e9t\u00e9 \u00e9galement charg\u00e9 de la construction du chemin de fer de Sfax \u00e0 Gafsa et Metlaoui.<\/p>\n<p>Cr\u00e9dit photo : Hatem Bourial<\/p>\n<p>C&rsquo;est non loin du port de Tunis, entre le viaduc et une friche urbaine, que se trouve le square qui porte son nom. Mais, ce square au c\u0153ur duquel se trouve un immeuble en ruines, est r\u00e9duit \u00e0 sa plus simple expression.<\/p>\n<p>Est-il possible de sauver cet \u00e9difice ? Est-ce normal d&rsquo;abandonner de la sorte, un patrimoine urbain ? Malheureusement, ce cas est loin d&rsquo;\u00eatre unique et la solution ne peut qu&rsquo;\u00eatre globale. En attendant, tant d&rsquo;immeubles d\u00e9p\u00e9rissent lentement, dans l&rsquo;indiff\u00e9rence g\u00e9n\u00e9rale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si l&rsquo;histoire a retenu le nom de ce grand entrepreneur, la Tunisie l&rsquo;a compl\u00e8tement oubli\u00e9.<\/p>\n","protected":false},"author":3229,"featured_media":290183,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2596],"tags":[9979,5983,2640],"class_list":["post-212079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","tag-louis-wiriot","tag-petite-sicile","tag-tunis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e<\/title>\n<meta name=\"description\" content=\"Si l&#039;histoire a retenu le nom de ce grand entrepreneur, la Tunisie l&#039;a compl\u00e8tement oubli\u00e9.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Si l&#039;histoire a retenu le nom de ce grand entrepreneur, la Tunisie l&#039;a compl\u00e8tement oubli\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/hatem.bourial.2025\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-06T10:34:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2024\/02\/b08115f5a2c7df439fbc97cd2bace976.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hatem Bourial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hatem Bourial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/\"},\"author\":{\"name\":\"Hatem Bourial\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\"},\"headline\":\"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e\",\"datePublished\":\"2024-02-06T10:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/\"},\"wordCount\":217,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/b08115f5a2c7df439fbc97cd2bace976.jpg\",\"keywords\":[\"'Louis Wiriot']\",\"Petite Sicile\",\"Tunis\"],\"articleSection\":[\"Chroniques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/\",\"name\":\"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/b08115f5a2c7df439fbc97cd2bace976.jpg\",\"datePublished\":\"2024-02-06T10:34:00+00:00\",\"description\":\"Si l'histoire a retenu le nom de ce grand entrepreneur, la Tunisie l'a compl\u00e8tement oubli\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/b08115f5a2c7df439fbc97cd2bace976.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/b08115f5a2c7df439fbc97cd2bace976.jpg\",\"width\":750,\"height\":400,\"caption\":\"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\\\/212079\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\",\"name\":\"Hatem Bourial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"caption\":\"Hatem Bourial\"},\"description\":\"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Fichier:Hatem_Bourial.jpg\"],\"knowsAbout\":[\"Culture & patrimoine tunisien\",\"Chronique soci\u00e9tale\",\"Litt\u00e9rature & m\u00e9moire\",\"Cin\u00e9ma & critique culturelle\",\"Identit\u00e9 & mutations sociales\"],\"knowsLanguage\":[\"Arabe\",\"Fran\u00e7ais\",\"Anglais\",\"Italien\",\"Polonais\"],\"jobTitle\":\"Journaliste, \u00e9crivain et chroniqueur culturel\",\"worksFor\":\"Webdo\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/hatem-bourial-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e","description":"Si l'histoire a retenu le nom de ce grand entrepreneur, la Tunisie l'a compl\u00e8tement oubli\u00e9.","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/","og_locale":"fr_FR","og_type":"article","og_title":"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e","og_description":"Si l'histoire a retenu le nom de ce grand entrepreneur, la Tunisie l'a compl\u00e8tement oubli\u00e9.","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_author":"https:\/\/www.facebook.com\/hatem.bourial.2025","article_published_time":"2024-02-06T10:34:00+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2024\/02\/b08115f5a2c7df439fbc97cd2bace976.jpg","type":"image\/jpeg"}],"author":"Hatem Bourial","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"Hatem Bourial","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/"},"author":{"name":"Hatem Bourial","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f"},"headline":"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e","datePublished":"2024-02-06T10:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/"},"wordCount":217,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2024\/02\/b08115f5a2c7df439fbc97cd2bace976.jpg","keywords":["'Louis Wiriot']","Petite Sicile","Tunis"],"articleSection":["Chroniques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/","name":"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2024\/02\/b08115f5a2c7df439fbc97cd2bace976.jpg","datePublished":"2024-02-06T10:34:00+00:00","description":"Si l'histoire a retenu le nom de ce grand entrepreneur, la Tunisie l'a compl\u00e8tement oubli\u00e9.","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2024\/02\/b08115f5a2c7df439fbc97cd2bace976.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2024\/02\/b08115f5a2c7df439fbc97cd2bace976.jpg","width":750,"height":400,"caption":"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-immeuble-en-ruines-un-square-desert-et-une-memoire-oubliee\/212079\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Un immeuble en ruines, un square d\u00e9sert et une m\u00e9moire oubli\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f","name":"Hatem Bourial","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","caption":"Hatem Bourial"},"description":"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\/\/www.facebook.com\/hatem.bourial.2025","sameAs":["https:\/\/www.facebook.com\/hatem.bourial.2025","https:\/\/fr.wikipedia.org\/wiki\/Fichier:Hatem_Bourial.jpg"],"knowsAbout":["Culture & patrimoine tunisien","Chronique soci\u00e9tale","Litt\u00e9rature & m\u00e9moire","Cin\u00e9ma & critique culturelle","Identit\u00e9 & mutations sociales"],"knowsLanguage":["Arabe","Fran\u00e7ais","Anglais","Italien","Polonais"],"jobTitle":"Journaliste, \u00e9crivain et chroniqueur culturel","worksFor":"Webdo","url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/hatem-bourial-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/212079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3229"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=212079"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/212079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/290183"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=212079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=212079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=212079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}