{"id":209766,"date":"2023-10-31T10:02:00","date_gmt":"2023-10-31T10:02:00","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/blog\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/"},"modified":"2023-10-31T10:02:00","modified_gmt":"2023-10-31T10:02:00","slug":"la-memoire-de-jazy-epicerie-de-la-rue-d-espagne","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/","title":{"rendered":"La m\u00e9moire de Jazy, \u00e9picerie de la rue d&rsquo;Espagne ?"},"content":{"rendered":"<p>Plusieurs g\u00e9n\u00e9rations se souviennent de l&rsquo;\u00e9picerie fine Jazy. Aujourd&rsquo;hui, il ne reste de cette enseigne que le souvenir d&rsquo;une \u00e9poque.<\/p>\n<p>\t\t\t\t\t\t\t\t\tEn plein milieu de la rue d\u2019Espagne, l\u2019\u00e9picerie fine Jazy est d\u00e9sormais introuvable. En effet, ce sont de nouveaux commerces d\u2019habillement qui sont venus occuper son emplacement, jadis connu de tous (photo).<\/p>\n<p>L\u2019\u00e9picerie Jazy \u00e9tait une v\u00e9ritable b\u00e9n\u00e9diction pour ses clients. On y trouvait tout et surtout les choses les plus rares. Les clients venaient d\u2019ailleurs de loin pour s\u2019y approvisionner et repartaient toujours satisfaits.<\/p>\n<p>Pleinement \u00e9tablie, la r\u00e9putation de Jazy a fait de ce magasin un v\u00e9ritable embl\u00e8me et une adresse incontournable.<\/p>\n<p>L\u2019\u00e9picerie se trouvait donc rue d\u2019Espagne, non loin de Bondin, du March\u00e9 central et de la Poste. Malheureusement, les photos de l\u2019\u00e9picerie Jazy sont introuvables, m\u00eame si la m\u00e9moire des lieux reste pr\u00e9sente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En plein milieu de la rue d\u2019Espagne, l\u2019\u00e9picerie fine Jazy est d\u00e9sormais introuvable. En effet, ce sont de nouveaux commerces d\u2019habillement qui sont venus occupe&#8230;<\/p>\n","protected":false},"author":3229,"featured_media":248931,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2596],"tags":[7655,2640],"class_list":["post-209766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","tag-jazy","tag-tunis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La m\u00e9moire de Jazy, \u00e9picerie de la rue d&#039;Espagne ?<\/title>\n<meta name=\"description\" content=\"En plein milieu de la rue d\u2019Espagne, l\u2019\u00e9picerie fine Jazy est d\u00e9sormais introuvable. En effet, ce sont de nouveaux commerces d\u2019habillement qui sont venus occupe...\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La m\u00e9moire de Jazy, \u00e9picerie de la rue d&#039;Espagne ?\" \/>\n<meta property=\"og:description\" content=\"En plein milieu de la rue d\u2019Espagne, l\u2019\u00e9picerie fine Jazy est d\u00e9sormais introuvable. En effet, ce sont de nouveaux commerces d\u2019habillement qui sont venus occupe...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/hatem.bourial.2025\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-31T10:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/10\/380471b5bdb9f5b46f3de741badb82bf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hatem Bourial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hatem Bourial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/\"},\"author\":{\"name\":\"Hatem Bourial\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\"},\"headline\":\"La m\u00e9moire de Jazy, \u00e9picerie de la rue d&rsquo;Espagne ?\",\"datePublished\":\"2023-10-31T10:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/\"},\"wordCount\":171,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/380471b5bdb9f5b46f3de741badb82bf.jpg\",\"keywords\":[\"jazy\",\"Tunis\"],\"articleSection\":[\"Chroniques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/\",\"name\":\"La m\u00e9moire de Jazy, \u00e9picerie de la rue d'Espagne ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/380471b5bdb9f5b46f3de741badb82bf.jpg\",\"datePublished\":\"2023-10-31T10:02:00+00:00\",\"description\":\"En plein milieu de la rue d\u2019Espagne, l\u2019\u00e9picerie fine Jazy est d\u00e9sormais introuvable. En effet, ce sont de nouveaux commerces d\u2019habillement qui sont venus occupe...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/380471b5bdb9f5b46f3de741badb82bf.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/380471b5bdb9f5b46f3de741badb82bf.jpg\",\"width\":750,\"height\":400,\"caption\":\"La m\u00e9moire de Jazy, \u00e9picerie de la rue d'Espagne ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\\\/209766\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La m\u00e9moire de Jazy, \u00e9picerie de la rue d&#8217;Espagne ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\",\"name\":\"Hatem Bourial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"caption\":\"Hatem Bourial\"},\"description\":\"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Fichier:Hatem_Bourial.jpg\"],\"knowsAbout\":[\"Culture & patrimoine tunisien\",\"Chronique soci\u00e9tale\",\"Litt\u00e9rature & m\u00e9moire\",\"Cin\u00e9ma & critique culturelle\",\"Identit\u00e9 & mutations sociales\"],\"knowsLanguage\":[\"Arabe\",\"Fran\u00e7ais\",\"Anglais\",\"Italien\",\"Polonais\"],\"jobTitle\":\"Journaliste, \u00e9crivain et chroniqueur culturel\",\"worksFor\":\"Webdo\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/hatem-bourial-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La m\u00e9moire de Jazy, \u00e9picerie de la rue d'Espagne ?","description":"En plein milieu de la rue d\u2019Espagne, l\u2019\u00e9picerie fine Jazy est d\u00e9sormais introuvable. En effet, ce sont de nouveaux commerces d\u2019habillement qui sont venus occupe...","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/","og_locale":"fr_FR","og_type":"article","og_title":"La m\u00e9moire de Jazy, \u00e9picerie de la rue d'Espagne ?","og_description":"En plein milieu de la rue d\u2019Espagne, l\u2019\u00e9picerie fine Jazy est d\u00e9sormais introuvable. En effet, ce sont de nouveaux commerces d\u2019habillement qui sont venus occupe...","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_author":"https:\/\/www.facebook.com\/hatem.bourial.2025","article_published_time":"2023-10-31T10:02:00+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/10\/380471b5bdb9f5b46f3de741badb82bf.jpg","type":"image\/jpeg"}],"author":"Hatem Bourial","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"Hatem Bourial","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/"},"author":{"name":"Hatem Bourial","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f"},"headline":"La m\u00e9moire de Jazy, \u00e9picerie de la rue d&rsquo;Espagne ?","datePublished":"2023-10-31T10:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/"},"wordCount":171,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/10\/380471b5bdb9f5b46f3de741badb82bf.jpg","keywords":["jazy","Tunis"],"articleSection":["Chroniques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/","name":"La m\u00e9moire de Jazy, \u00e9picerie de la rue d'Espagne ?","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/10\/380471b5bdb9f5b46f3de741badb82bf.jpg","datePublished":"2023-10-31T10:02:00+00:00","description":"En plein milieu de la rue d\u2019Espagne, l\u2019\u00e9picerie fine Jazy est d\u00e9sormais introuvable. En effet, ce sont de nouveaux commerces d\u2019habillement qui sont venus occupe...","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/10\/380471b5bdb9f5b46f3de741badb82bf.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/10\/380471b5bdb9f5b46f3de741badb82bf.jpg","width":750,"height":400,"caption":"La m\u00e9moire de Jazy, \u00e9picerie de la rue d'Espagne ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/la-memoire-de-jazy-epicerie-de-la-rue-d-espagne\/209766\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"La m\u00e9moire de Jazy, \u00e9picerie de la rue d&#8217;Espagne ?"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f","name":"Hatem Bourial","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","caption":"Hatem Bourial"},"description":"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\/\/www.facebook.com\/hatem.bourial.2025","sameAs":["https:\/\/www.facebook.com\/hatem.bourial.2025","https:\/\/fr.wikipedia.org\/wiki\/Fichier:Hatem_Bourial.jpg"],"knowsAbout":["Culture & patrimoine tunisien","Chronique soci\u00e9tale","Litt\u00e9rature & m\u00e9moire","Cin\u00e9ma & critique culturelle","Identit\u00e9 & mutations sociales"],"knowsLanguage":["Arabe","Fran\u00e7ais","Anglais","Italien","Polonais"],"jobTitle":"Journaliste, \u00e9crivain et chroniqueur culturel","worksFor":"Webdo","url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/hatem-bourial-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/209766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3229"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=209766"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/209766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/248931"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=209766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=209766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=209766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}