{"id":208284,"date":"2023-08-30T12:53:00","date_gmt":"2023-08-30T12:53:00","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/blog\/nostalgies-dans-les-galeries-du-colisee\/208284\/"},"modified":"2023-08-30T12:53:00","modified_gmt":"2023-08-30T12:53:00","slug":"nostalgies-dans-les-galeries-du-colisee","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/","title":{"rendered":"Nostalgies : Dans les galeries du Colis\u00e9e"},"content":{"rendered":"<p>Espace commercial historique, le Colis\u00e9e est bien plus qu&rsquo;un cin\u00e9ma. Ses galeries regorgent de boutiques mythiques dont certaines font d\u00e9sormais partie de la m\u00e9moire collective.<\/p>\n<p>\t\t\t\t\t\t\t\t\tUne envie tenace de me plonger dans un puzzle : celui des galeries du Colis\u00e9e qui sont l&rsquo;un des premiers espaces commerciaux au c\u0153ur de Tunis.<\/p>\n<p>On y entre par quatre acc\u00e8s diff\u00e9rents : les deux portes de l&rsquo;avenue Bourguiba, celle de l&rsquo;avenue de Paris et celle de la rue de Marseille.<\/p>\n<p>\u00c0 l&rsquo;int\u00e9rieur, la Rotonde et le Kilt sont les deux caf\u00e9s qui structurent les lieux, en face de la vol\u00e9e de marches qui permettent d&rsquo;acc\u00e9der \u00e0 la reine des salles de cin\u00e9ma de Tunis.<\/p>\n<p>Temple mythique du septi\u00e8me art, avec ses exclusivit\u00e9s, sa mezzanine, son balcon et son toit ouvrant, le Colis\u00e9e a \u00e9galement accueilli les stars des ann\u00e9es cinquante pour des concerts m\u00e9morables.<\/p>\n<p>\u00c0 droite du cin\u00e9ma, le studio du photographe Guyse et \u00e0 gauche, un marchand de disques qui, d\u00e9sormais, a c\u00e9d\u00e9 son emplacement \u00e0 un bijoutier.<\/p>\n<p>Au Colis\u00e9e, les bijoutiers les plus connus sont Andr\u00e9 Cordina (dont le magasin est d\u00e9sormais exploit\u00e9 par la famille Addario) et Ben Youssef qui a maintenu son activit\u00e9.<\/p>\n<p>Les boutiques innombrables sont alentour : Big Ben o\u00f9 B\u00e9b\u00e9 Slama a longtemps vendu des montres, Latino qui fut un coiffeur tr\u00e8s recherch\u00e9, La Parisienne o\u00f9 convergeaient les \u00e9l\u00e9gantes aux bons soins de Germaine.<\/p>\n<p>Comment ne pas citer Domino, les magasins de disques de Montassar Ayachi et des Ben Sedrine, Nemrod et les tenues de sport qu&rsquo;y vendait Abderahman Ben Ezzeddine, La M\u00e8re et l&rsquo;enfant et ses jouets, le Crazy Horse ou le salon de coiffure Figaro ?<\/p>\n<p>Les m\u00e9andres du Colis\u00e9e sont infinis et la m\u00e9moire peut s&rsquo;y perdre. Je les arpente mentalement, en attendant de retrouver d&rsquo;autres traces.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Espace commercial historique, le Colis\u00e9e est bien plus qu&rsquo;un cin\u00e9ma. Ses galeries regorgent de boutiques mythiques dont certaines font d\u00e9sormais partie de la m\u00e9&#8230;<\/p>\n","protected":false},"author":3229,"featured_media":249435,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2596],"tags":[4808],"class_list":["post-208284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","tag-colisee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nostalgies : Dans les galeries du Colis\u00e9e<\/title>\n<meta name=\"description\" content=\"Espace commercial historique, le Colis\u00e9e est bien plus qu&#039;un cin\u00e9ma. Ses galeries regorgent de boutiques mythiques dont certaines font d\u00e9sormais partie de la m\u00e9...\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nostalgies : Dans les galeries du Colis\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Espace commercial historique, le Colis\u00e9e est bien plus qu&#039;un cin\u00e9ma. Ses galeries regorgent de boutiques mythiques dont certaines font d\u00e9sormais partie de la m\u00e9...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/hatem.bourial.2025\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-30T12:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/08\/5c0e7e4fb9bd689edffaae1adce895f1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hatem Bourial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hatem Bourial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/\"},\"author\":{\"name\":\"Hatem Bourial\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\"},\"headline\":\"Nostalgies : Dans les galeries du Colis\u00e9e\",\"datePublished\":\"2023-08-30T12:53:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/5c0e7e4fb9bd689edffaae1adce895f1.jpg\",\"keywords\":[\"colis\u00e9e\"],\"articleSection\":[\"Chroniques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/\",\"name\":\"Nostalgies : Dans les galeries du Colis\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/5c0e7e4fb9bd689edffaae1adce895f1.jpg\",\"datePublished\":\"2023-08-30T12:53:00+00:00\",\"description\":\"Espace commercial historique, le Colis\u00e9e est bien plus qu'un cin\u00e9ma. Ses galeries regorgent de boutiques mythiques dont certaines font d\u00e9sormais partie de la m\u00e9...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/5c0e7e4fb9bd689edffaae1adce895f1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/5c0e7e4fb9bd689edffaae1adce895f1.jpg\",\"width\":720,\"height\":384,\"caption\":\"Nostalgies : Dans les galeries du Colis\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/nostalgies-dans-les-galeries-du-colisee\\\/208284\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nostalgies : Dans les galeries du Colis\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\",\"name\":\"Hatem Bourial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"caption\":\"Hatem Bourial\"},\"description\":\"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Fichier:Hatem_Bourial.jpg\"],\"knowsAbout\":[\"Culture & patrimoine tunisien\",\"Chronique soci\u00e9tale\",\"Litt\u00e9rature & m\u00e9moire\",\"Cin\u00e9ma & critique culturelle\",\"Identit\u00e9 & mutations sociales\"],\"knowsLanguage\":[\"Arabe\",\"Fran\u00e7ais\",\"Anglais\",\"Italien\",\"Polonais\"],\"jobTitle\":\"Journaliste, \u00e9crivain et chroniqueur culturel\",\"worksFor\":\"Webdo\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/hatem-bourial-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nostalgies : Dans les galeries du Colis\u00e9e","description":"Espace commercial historique, le Colis\u00e9e est bien plus qu'un cin\u00e9ma. Ses galeries regorgent de boutiques mythiques dont certaines font d\u00e9sormais partie de la m\u00e9...","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/","og_locale":"fr_FR","og_type":"article","og_title":"Nostalgies : Dans les galeries du Colis\u00e9e","og_description":"Espace commercial historique, le Colis\u00e9e est bien plus qu'un cin\u00e9ma. Ses galeries regorgent de boutiques mythiques dont certaines font d\u00e9sormais partie de la m\u00e9...","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_author":"https:\/\/www.facebook.com\/hatem.bourial.2025","article_published_time":"2023-08-30T12:53:00+00:00","og_image":[{"width":720,"height":384,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/08\/5c0e7e4fb9bd689edffaae1adce895f1.jpg","type":"image\/jpeg"}],"author":"Hatem Bourial","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"Hatem Bourial","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/"},"author":{"name":"Hatem Bourial","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f"},"headline":"Nostalgies : Dans les galeries du Colis\u00e9e","datePublished":"2023-08-30T12:53:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/08\/5c0e7e4fb9bd689edffaae1adce895f1.jpg","keywords":["colis\u00e9e"],"articleSection":["Chroniques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/","name":"Nostalgies : Dans les galeries du Colis\u00e9e","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/08\/5c0e7e4fb9bd689edffaae1adce895f1.jpg","datePublished":"2023-08-30T12:53:00+00:00","description":"Espace commercial historique, le Colis\u00e9e est bien plus qu'un cin\u00e9ma. Ses galeries regorgent de boutiques mythiques dont certaines font d\u00e9sormais partie de la m\u00e9...","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/08\/5c0e7e4fb9bd689edffaae1adce895f1.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/08\/5c0e7e4fb9bd689edffaae1adce895f1.jpg","width":720,"height":384,"caption":"Nostalgies : Dans les galeries du Colis\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/nostalgies-dans-les-galeries-du-colisee\/208284\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Nostalgies : Dans les galeries du Colis\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f","name":"Hatem Bourial","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","caption":"Hatem Bourial"},"description":"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\/\/www.facebook.com\/hatem.bourial.2025","sameAs":["https:\/\/www.facebook.com\/hatem.bourial.2025","https:\/\/fr.wikipedia.org\/wiki\/Fichier:Hatem_Bourial.jpg"],"knowsAbout":["Culture & patrimoine tunisien","Chronique soci\u00e9tale","Litt\u00e9rature & m\u00e9moire","Cin\u00e9ma & critique culturelle","Identit\u00e9 & mutations sociales"],"knowsLanguage":["Arabe","Fran\u00e7ais","Anglais","Italien","Polonais"],"jobTitle":"Journaliste, \u00e9crivain et chroniqueur culturel","worksFor":"Webdo","url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/hatem-bourial-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/208284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3229"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=208284"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/208284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/249435"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=208284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=208284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=208284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}