{"id":206266,"date":"2023-06-02T08:44:00","date_gmt":"2023-06-02T08:44:00","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/blog\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/"},"modified":"2025-05-14T10:40:50","modified_gmt":"2025-05-14T10:40:50","slug":"un-italiano-vero-dans-les-rues-de-tunis","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/","title":{"rendered":"\u00ab\u00a0Un Italiano Vero\u00a0\u00bb dans les rues de Tunis"},"content":{"rendered":"<p>Loin des flonflons de la f\u00eate et en communion avec toutes les g\u00e9n\u00e9rations d&rsquo;Italiens de Tunisie, nous \u00e9tions trois \u00e0 avoir d\u00e9cid\u00e9 de c\u00e9l\u00e9brer la R\u00e9publique italienne en nous engageant dans une longue promenade dans la ville de Tunis et ses deux versants.<\/p>\n<p>\t\t\t\t\t\t\t\t\tTania et Paolo viennent de la r\u00e9gion de Florence, quelque part dans ce triangle magique ou rayonnent \u00e9galement Sienne et Bologne. D&rsquo;une certaine mani\u00e8re, leur italianit\u00e9 diff\u00e8re de celle des Siciliens, des Calabrais, des Sardes et des Napolitains qui ont \u00e9t\u00e9 nombreux \u00e0 peupler Tunis et ses environs.<\/p>\n<p>Palazzo Gnecco, Tunis (Photo : Mounir Azizi)<\/p>\n<p>Ils sont d&rsquo;ailleurs encore pr\u00e9sents, dans les lieux qu&rsquo;ils ont fait vivre, du Kram avec les Baiada \u00e0 Saint-Henri avec les Curti. Souvent, je retrouve des amis aux origines italiennes dont certains ont choisi de s&rsquo;assimiler compl\u00e8tement au pays natal et \u00e0 celui de leurs anc\u00eatres, venus au dix-neuvi\u00e8me si\u00e8cle.<\/p>\n<p>Pour cette qu\u00eate des traces italiennes dans Tunis, nous avons choisi de commencer par le Quartier franc du dix-septi\u00e8me si\u00e8cle, en allant \u00e0 la recherche des anciens caravans\u00e9rails de Sardaigne et du Royaume des Deux-Siciles.<\/p>\n<p>Nous avons ensuite retrouv\u00e9 les \u00e9chos du palazzo Gnecco qui se souvient encore de la pr\u00e9sence de Garibaldi, Fedriani et plusieurs r\u00e9fugi\u00e9s qui avaient trouv\u00e9 \u00e0 Tunis, un havre accueillant et l&rsquo;asile politique.<\/p>\n<p>La b\u00e2tisse de la maison Gnecco est impressionnante. Tania prononce le mot \u00ab\u00a0Gattopardo\u00a0\u00bb comme pour nous projeter dans un film de Visconti. Nous admirons les portes ouvrag\u00e9es et les colonnes en marbre de Carrare qui ornent les escaliers. J&rsquo;\u00e9voque la longue saga familiale des \u00c9vang\u00e9listi dont l&rsquo;un des membres fut pour un temps, antiquaire dans l&rsquo;un des appartements du palais.<\/p>\n<p>Rue d&rsquo;Italie<\/p>\n<p>L&rsquo;\u00e9glise Sainte Croix est notre prochaine \u00e9tape. J&rsquo;y rappelle la longue histoire des Capucins et celle des nombreuses congr\u00e9gations italiennes qui ont anim\u00e9 la spiritualit\u00e9 et l&rsquo;action sociale dans ces quartiers populeux d&rsquo;une m\u00e9dina qui ne parlait que l&rsquo;idiome sicilien.<\/p>\n<p>Nos pas nous m\u00e8neront d&rsquo;ailleurs jusqu&rsquo;\u00e0 l&rsquo;\u00e9glise du Rosaire qui se trouve \u00e0 l&rsquo;autre bout de la ville. Nous irons aussi sur les traces des deux chapelles qui se trouvaient \u00e0 la rue de la Sebkha, non loin de l&rsquo;impasse du Foss\u00e9, l\u00e0 o\u00f9 hors les murs, ont v\u00e9cu les premi\u00e8res communaut\u00e9s italiennes.<\/p>\n<p>Le souvenir remonte \u00e0 chaque pas. Ici, la boulangerie Musso, l\u00e0 l&rsquo;atelier de menuiser d&rsquo;Yvo Salerno, plus loin se trouvaient le salon de coiffure de Giuseppe, la boutique de Campo, le tailleur Salvatore, le sertisseur Settimo Spina et tant d&rsquo;autres que je pourrais nommer un par un.<\/p>\n<p>Les anecdotes fusent et des bribes de m\u00e9moire jaillissent entre la rue El Mektar et le souk des Teinturiers. Nous choisissons de remonter le boulevard jusqu&rsquo;\u00e0 la porte Bab Djedid. L&rsquo;ancien lyc\u00e9e italien est toujours l\u00e0 ainsi que les immeubles dont on dirait qu&rsquo;ils surgissent d&rsquo;une ruelle palermitaine. Les \u00e9chos des voix et des visages s&rsquo;incrustent et ont aussi la saveur de la caponate d&rsquo;aubergines ou des gnocchi aux pommes de terre.<\/p>\n<p>Familles siciliennes<\/p>\n<p>Je revis dans ma peau italienne, pr\u00e8s de la Porte Neuve, entre la rue des Silos et la rue de l&rsquo;Hiver. Le local du Club Africain est ouvert. Nous y entrons et je feins de demander le nom de l&rsquo;entra\u00eeneur italien qui avait milit\u00e9 au club. La r\u00e9ponse fuse prompte : \u00ab\u00a0Fabio\u00a0\u00bb. Et je raconte le myst\u00e9rieux bloc-notes du grand Fabio Rocheggiani lorsque sur le banc de touche, il dessinait alors que tous pensaient qu&rsquo;il dressait des sch\u00e9mas tactiques. Car Fabio fut aussi artiste peintre.<\/p>\n<p>Au c\u0153ur de la m\u00e9dina, nous croisons Raimondo Fassa, un intellectuel de premier plan, qui a longtemps v\u00e9cu entre la rue El Kobbi et le passage Sidi Abderraouf.<\/p>\n<p>Aujourd&rsquo;hui, il habite rue Boukhris, pr\u00e8s de la demeure de mes a\u00efeux. Nous \u00e9voquons la m\u00e9moire italienne et en particulier celle des Livournais dont nous traversons le souk qu&rsquo;ils avaient cr\u00e9\u00e9 \u00e0 Tunis \u00e0 l&rsquo;enseigne des Grana.<\/p>\n<p>Sur l&rsquo;autre versant de la ville, une autre Petite Sicile nous attend : celle qui est n\u00e9e de la patience de la signora Fasciotti qui achetait toute la pierre de la m\u00e9dina pour remblayer la lagune et b\u00e2tir un nouveau quartier.<\/p>\n<p>Dans ces m\u00e9andres, voici le Politeama Rossini dont le fronton fut longtemps orn\u00e9 de l&rsquo;effigie du musicien. Un m\u00e9daillon vide porte encore cette trace en creux, sur la fa\u00e7ade de ce th\u00e9\u00e2tre italien cr\u00e9\u00e9 en 1903.<\/p>\n<p>Lyc\u00e9e italien de Bab Djedid<\/p>\n<p>Plus loin, la maison Ibn Khaldoun se souvient encore qu&rsquo;elle fut le si\u00e8ge de la Dante Alighieri. L&rsquo;architecture florentine de l&rsquo;\u00e9difice le sugg\u00e8re tout comme la t\u00eate dans les nuages, le palazzo Designi r\u00eave \u00e0 une lointaine Venise.<\/p>\n<p>Les noms me reviennent : Carollo, Bonfiglio, Checca, Bertolino, Di Trapani, Cordaro, Tedeschi, Mineo, Santonocitto, Luciani, Canio. Les noms se m\u00ealent aux enseignes : Pino, Di Carlo, Cacciola, le Paradiso, le Circolo, l&rsquo;op\u00e9ra dei Puppi qui se trouvait \u00e0 la rue El Marr.<\/p>\n<p>La d\u00e9ambulation continue, les yeux sur l&rsquo;\u0153uvre des ma\u00e7ons italiens. Ce sont des mains souvent siciliennes qui ont b\u00e2ti les demeures, d\u00e9frich\u00e9 la terre, r\u00eav\u00e9 d&rsquo;un avenir africain qui aurait eu les saveurs de la p\u00e9ninsule du Cap Bon et des rives de la Medjerda.<\/p>\n<p>Tania et Paolo n&rsquo;en reviennent pas et se prom\u00e8nent d&rsquo;une Petite Sicile \u00e0 une autre, se retrouvent \u00e0 la Goulette, \u00e0 l&rsquo;ombre de l&rsquo;\u00e9glise catholique et de Notre-Dame de Trapani puis, mentalement, retraversent toutes ces Italies virtuelles que nous avons juste effleur\u00e9es.<\/p>\n<p>En gage d&rsquo;amiti\u00e9, ils m&rsquo;offrent une marionnette \u00e0 l&rsquo;effigie de Pinocchio, ce qui, instantan\u00e9ment, me renvoie aux lectures de l&rsquo;enfance et \u00e0 d&rsquo;autres h\u00e9ros comme Scaramuzza.<\/p>\n<p>Migrants italiens<\/p>\n<p>D\u00e9sormais\u00a0 j&rsquo;ai l&rsquo;\u00e2ge de Gepetto mais cela ne m&#8217;emp\u00eachera pas de jouer avec cette marionnette inattendue mais qui tombe \u00e0 point. Ce devait \u00eatre \u00e9crit quelque part que je recevrai ce Pinocchio, un premier juin au moment m\u00eame o\u00f9, bien loin, \u00e0 Vienne, une poup\u00e9e sicilienne et un film t\u00e9moignent de ma participation \u00e0 un \u00e9v\u00e9nement artistique.<\/p>\n<p>Ne dit-on pas que le hasard fait bien les choses ? Ne dit-on pas aussi, avec justesse, que nous avons tous en nous quelque chose d&rsquo;Italie ? N&rsquo;est-il pas \u00e9galement vrai qu&rsquo;une simple promenade peut r\u00e9veiller des nostalgies insoup\u00e7onn\u00e9es ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Loin des flonflons de la f\u00eate et en communion avec toutes les g\u00e9n\u00e9rations d&rsquo;Italiens de Tunisie, nous \u00e9tions trois \u00e0 avoir d\u00e9cid\u00e9 de c\u00e9l\u00e9brer la R\u00e9publique ital&#8230;<\/p>\n","protected":false},"author":3229,"featured_media":250992,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2596],"tags":[2660,8354,2640,2608],"class_list":["post-206266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","tag-italie","tag-italiens","tag-tunis","tag-tunisie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un Italiano Vero dans les rues de Tunis<\/title>\n<meta name=\"description\" content=\"Loin des flonflons de la f\u00eate et en communion avec toutes les g\u00e9n\u00e9rations d&#039;Italiens de Tunisie, nous \u00e9tions trois \u00e0 avoir d\u00e9cid\u00e9 de c\u00e9l\u00e9brer la R\u00e9publique ital...\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Un Italiano Vero&quot; dans les rues de Tunis\" \/>\n<meta property=\"og:description\" content=\"Loin des flonflons de la f\u00eate et en communion avec toutes les g\u00e9n\u00e9rations d&#039;Italiens de Tunisie, nous \u00e9tions trois \u00e0 avoir d\u00e9cid\u00e9 de c\u00e9l\u00e9brer la R\u00e9publique ital...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/hatem.bourial.2025\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-02T08:44:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-14T10:40:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/06\/78e9a3bf662c514350d4932f2dbb95bd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hatem Bourial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hatem Bourial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/\"},\"author\":{\"name\":\"Hatem Bourial\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\"},\"headline\":\"\u00ab\u00a0Un Italiano Vero\u00a0\u00bb dans les rues de Tunis\",\"datePublished\":\"2023-06-02T08:44:00+00:00\",\"dateModified\":\"2025-05-14T10:40:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/\"},\"wordCount\":1128,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/78e9a3bf662c514350d4932f2dbb95bd.jpg\",\"keywords\":[\"Italie\",\"italiens\",\"Tunis\",\"Tunisie\"],\"articleSection\":[\"Chroniques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/\",\"name\":\"Un Italiano Vero dans les rues de Tunis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/78e9a3bf662c514350d4932f2dbb95bd.jpg\",\"datePublished\":\"2023-06-02T08:44:00+00:00\",\"dateModified\":\"2025-05-14T10:40:50+00:00\",\"description\":\"Loin des flonflons de la f\u00eate et en communion avec toutes les g\u00e9n\u00e9rations d'Italiens de Tunisie, nous \u00e9tions trois \u00e0 avoir d\u00e9cid\u00e9 de c\u00e9l\u00e9brer la R\u00e9publique ital...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/78e9a3bf662c514350d4932f2dbb95bd.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/78e9a3bf662c514350d4932f2dbb95bd.jpg\",\"width\":720,\"height\":384,\"caption\":\"Palazzo Gnecco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/un-italiano-vero-dans-les-rues-de-tunis\\\/206266\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Un Italiano Vero&#8221; dans les rues de Tunis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\",\"name\":\"Hatem Bourial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"caption\":\"Hatem Bourial\"},\"description\":\"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Fichier:Hatem_Bourial.jpg\"],\"knowsAbout\":[\"Culture & patrimoine tunisien\",\"Chronique soci\u00e9tale\",\"Litt\u00e9rature & m\u00e9moire\",\"Cin\u00e9ma & critique culturelle\",\"Identit\u00e9 & mutations sociales\"],\"knowsLanguage\":[\"Arabe\",\"Fran\u00e7ais\",\"Anglais\",\"Italien\",\"Polonais\"],\"jobTitle\":\"Journaliste, \u00e9crivain et chroniqueur culturel\",\"worksFor\":\"Webdo\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/hatem-bourial-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un Italiano Vero dans les rues de Tunis","description":"Loin des flonflons de la f\u00eate et en communion avec toutes les g\u00e9n\u00e9rations d'Italiens de Tunisie, nous \u00e9tions trois \u00e0 avoir d\u00e9cid\u00e9 de c\u00e9l\u00e9brer la R\u00e9publique ital...","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/","og_locale":"fr_FR","og_type":"article","og_title":"\"Un Italiano Vero\" dans les rues de Tunis","og_description":"Loin des flonflons de la f\u00eate et en communion avec toutes les g\u00e9n\u00e9rations d'Italiens de Tunisie, nous \u00e9tions trois \u00e0 avoir d\u00e9cid\u00e9 de c\u00e9l\u00e9brer la R\u00e9publique ital...","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_author":"https:\/\/www.facebook.com\/hatem.bourial.2025","article_published_time":"2023-06-02T08:44:00+00:00","article_modified_time":"2025-05-14T10:40:50+00:00","og_image":[{"width":720,"height":384,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/06\/78e9a3bf662c514350d4932f2dbb95bd.jpg","type":"image\/jpeg"}],"author":"Hatem Bourial","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"Hatem Bourial","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/"},"author":{"name":"Hatem Bourial","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f"},"headline":"\u00ab\u00a0Un Italiano Vero\u00a0\u00bb dans les rues de Tunis","datePublished":"2023-06-02T08:44:00+00:00","dateModified":"2025-05-14T10:40:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/"},"wordCount":1128,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/06\/78e9a3bf662c514350d4932f2dbb95bd.jpg","keywords":["Italie","italiens","Tunis","Tunisie"],"articleSection":["Chroniques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/","name":"Un Italiano Vero dans les rues de Tunis","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/06\/78e9a3bf662c514350d4932f2dbb95bd.jpg","datePublished":"2023-06-02T08:44:00+00:00","dateModified":"2025-05-14T10:40:50+00:00","description":"Loin des flonflons de la f\u00eate et en communion avec toutes les g\u00e9n\u00e9rations d'Italiens de Tunisie, nous \u00e9tions trois \u00e0 avoir d\u00e9cid\u00e9 de c\u00e9l\u00e9brer la R\u00e9publique ital...","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/06\/78e9a3bf662c514350d4932f2dbb95bd.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/06\/78e9a3bf662c514350d4932f2dbb95bd.jpg","width":720,"height":384,"caption":"Palazzo Gnecco"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/un-italiano-vero-dans-les-rues-de-tunis\/206266\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"&#8220;Un Italiano Vero&#8221; dans les rues de Tunis"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f","name":"Hatem Bourial","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","caption":"Hatem Bourial"},"description":"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\/\/www.facebook.com\/hatem.bourial.2025","sameAs":["https:\/\/www.facebook.com\/hatem.bourial.2025","https:\/\/fr.wikipedia.org\/wiki\/Fichier:Hatem_Bourial.jpg"],"knowsAbout":["Culture & patrimoine tunisien","Chronique soci\u00e9tale","Litt\u00e9rature & m\u00e9moire","Cin\u00e9ma & critique culturelle","Identit\u00e9 & mutations sociales"],"knowsLanguage":["Arabe","Fran\u00e7ais","Anglais","Italien","Polonais"],"jobTitle":"Journaliste, \u00e9crivain et chroniqueur culturel","worksFor":"Webdo","url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/hatem-bourial-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/206266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3229"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=206266"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/206266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/250992"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=206266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=206266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=206266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}