{"id":204530,"date":"2023-04-04T08:46:00","date_gmt":"2023-04-04T08:46:00","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/blog\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/"},"modified":"2023-04-04T08:46:00","modified_gmt":"2023-04-04T08:46:00","slug":"judaisme-tunisien-le-depositoire-fait-peau-neuve","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/","title":{"rendered":"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve"},"content":{"rendered":"<p>Situ\u00e9 dans le quartier du Passage, le d\u00e9positoire Navarin se trouve dans la rue \u00e9ponyme, non loin du parc Habib Thameur qui avant d&rsquo;\u00eatre un jardin public, abritait le cimeti\u00e8re de la communaut\u00e9 juive de Tunis.<\/p>\n<p>\t\t\t\t\t\t\t\t\tC&rsquo;est par ce lieu rituel que transitent les d\u00e9pouilles mortelles avant les fun\u00e9railles et ce d\u00e9positoire continue \u00e0 avoir le m\u00eame usage.<\/p>\n<p>R\u00e9cemment des travaux ont \u00e9t\u00e9 entrepris et accomplis. Le r\u00e9sultat en est une r\u00e9novation compl\u00e8te des lieux qui retrouvent la sobri\u00e9t\u00e9 de leur architecture.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Situ\u00e9 dans le quartier du Passage, le d\u00e9positoire Navarin se trouve dans la rue \u00e9ponyme, non loin du parc Habib Thameur qui avant d&rsquo;\u00eatre un jardin public, abrit&#8230;<\/p>\n","protected":false},"author":3229,"featured_media":251530,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2596],"tags":[8597,2640],"class_list":["post-204530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","tag-depositoire","tag-tunis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve<\/title>\n<meta name=\"description\" content=\"Situ\u00e9 dans le quartier du Passage, le d\u00e9positoire Navarin se trouve dans la rue \u00e9ponyme, non loin du parc Habib Thameur qui avant d&#039;\u00eatre un jardin public, abrit...\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve\" \/>\n<meta property=\"og:description\" content=\"Situ\u00e9 dans le quartier du Passage, le d\u00e9positoire Navarin se trouve dans la rue \u00e9ponyme, non loin du parc Habib Thameur qui avant d&#039;\u00eatre un jardin public, abrit...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/hatem.bourial.2025\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-04T08:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/04\/98d8e3b9e8c61dadd5354ab090c4b7a3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hatem Bourial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hatem Bourial\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/\"},\"author\":{\"name\":\"Hatem Bourial\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\"},\"headline\":\"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve\",\"datePublished\":\"2023-04-04T08:46:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/\"},\"wordCount\":103,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/98d8e3b9e8c61dadd5354ab090c4b7a3.jpg\",\"keywords\":[\"d\u00e9positoire\",\"Tunis\"],\"articleSection\":[\"Chroniques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/\",\"name\":\"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/98d8e3b9e8c61dadd5354ab090c4b7a3.jpg\",\"datePublished\":\"2023-04-04T08:46:00+00:00\",\"description\":\"Situ\u00e9 dans le quartier du Passage, le d\u00e9positoire Navarin se trouve dans la rue \u00e9ponyme, non loin du parc Habib Thameur qui avant d'\u00eatre un jardin public, abrit...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/98d8e3b9e8c61dadd5354ab090c4b7a3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/98d8e3b9e8c61dadd5354ab090c4b7a3.jpg\",\"width\":750,\"height\":400,\"caption\":\"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/judaisme-tunisien-le-depositoire-fait-peau-neuve\\\/204530\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\",\"name\":\"Hatem Bourial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"caption\":\"Hatem Bourial\"},\"description\":\"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Fichier:Hatem_Bourial.jpg\"],\"knowsAbout\":[\"Culture & patrimoine tunisien\",\"Chronique soci\u00e9tale\",\"Litt\u00e9rature & m\u00e9moire\",\"Cin\u00e9ma & critique culturelle\",\"Identit\u00e9 & mutations sociales\"],\"knowsLanguage\":[\"Arabe\",\"Fran\u00e7ais\",\"Anglais\",\"Italien\",\"Polonais\"],\"jobTitle\":\"Journaliste, \u00e9crivain et chroniqueur culturel\",\"worksFor\":\"Webdo\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/hatem-bourial-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve","description":"Situ\u00e9 dans le quartier du Passage, le d\u00e9positoire Navarin se trouve dans la rue \u00e9ponyme, non loin du parc Habib Thameur qui avant d'\u00eatre un jardin public, abrit...","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/","og_locale":"fr_FR","og_type":"article","og_title":"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve","og_description":"Situ\u00e9 dans le quartier du Passage, le d\u00e9positoire Navarin se trouve dans la rue \u00e9ponyme, non loin du parc Habib Thameur qui avant d'\u00eatre un jardin public, abrit...","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_author":"https:\/\/www.facebook.com\/hatem.bourial.2025","article_published_time":"2023-04-04T08:46:00+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/04\/98d8e3b9e8c61dadd5354ab090c4b7a3.jpg","type":"image\/jpeg"}],"author":"Hatem Bourial","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"Hatem Bourial"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/"},"author":{"name":"Hatem Bourial","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f"},"headline":"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve","datePublished":"2023-04-04T08:46:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/"},"wordCount":103,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/04\/98d8e3b9e8c61dadd5354ab090c4b7a3.jpg","keywords":["d\u00e9positoire","Tunis"],"articleSection":["Chroniques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/","name":"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/04\/98d8e3b9e8c61dadd5354ab090c4b7a3.jpg","datePublished":"2023-04-04T08:46:00+00:00","description":"Situ\u00e9 dans le quartier du Passage, le d\u00e9positoire Navarin se trouve dans la rue \u00e9ponyme, non loin du parc Habib Thameur qui avant d'\u00eatre un jardin public, abrit...","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/04\/98d8e3b9e8c61dadd5354ab090c4b7a3.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2023\/04\/98d8e3b9e8c61dadd5354ab090c4b7a3.jpg","width":750,"height":400,"caption":"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/judaisme-tunisien-le-depositoire-fait-peau-neuve\/204530\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Juda\u00efsme tunisien : Le D\u00e9positoire fait peau neuve"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f","name":"Hatem Bourial","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","caption":"Hatem Bourial"},"description":"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\/\/www.facebook.com\/hatem.bourial.2025","sameAs":["https:\/\/www.facebook.com\/hatem.bourial.2025","https:\/\/fr.wikipedia.org\/wiki\/Fichier:Hatem_Bourial.jpg"],"knowsAbout":["Culture & patrimoine tunisien","Chronique soci\u00e9tale","Litt\u00e9rature & m\u00e9moire","Cin\u00e9ma & critique culturelle","Identit\u00e9 & mutations sociales"],"knowsLanguage":["Arabe","Fran\u00e7ais","Anglais","Italien","Polonais"],"jobTitle":"Journaliste, \u00e9crivain et chroniqueur culturel","worksFor":"Webdo","url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/hatem-bourial-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/204530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3229"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=204530"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/204530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/251530"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=204530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=204530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=204530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}