{"id":188266,"date":"2019-06-27T10:17:00","date_gmt":"2019-06-27T10:17:00","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/actualite\/blog\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/"},"modified":"2019-06-27T10:17:00","modified_gmt":"2019-06-27T10:17:00","slug":"une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/","title":{"rendered":"Une photo unique : Taxis d&rsquo;antan \u00e0 la queue leu leu sur l&rsquo;avenue"},"content":{"rendered":"<p>Les anciens vous le raconteront: jusqu&rsquo;au d\u00e9but des ann\u00e9es 1970, une station taxi se trouvait sur l&rsquo;avenue Bourguiba et rassemblait les voitures de prestige.<\/p>\n<p>Ces grands taxis comme nous les nommions \u00e9taient de belles berlines, en g\u00e9n\u00e9ral des Mercedes Benz, qui stationnaient en face du Th\u00e9\u00e2tre municipal.<\/p>\n<p>De l&rsquo;autre c\u00f4t\u00e9, en face du Colis\u00e9e, se trouvait la station des taxis b\u00e9b\u00e9 et tout le monde y trouvait son compte.<\/p>\n<p>Cette photo est plus ancienne. Toutefois, elle nous montre que la station de taxi face au Th\u00e9\u00e2tre municipal est des plus anciennes.<\/p>\n<p>Elle remonte certainement \u00e0 l&rsquo;\u00e9poque o\u00f9 Tunis s&rsquo;ouvrait au tourisme d&rsquo;hivernage et accueillait des visiteurs qui se r\u00e9partissaient dans ses grands h\u00f4tels et utilisaient ces taxis pour leurs visites \u00e0 Carthage ou au Bardo.<\/p>\n<p>Les h\u00f4tels de l&rsquo;\u00e9poque comptaient sur ces taxis disponibles \u00e0 toute heure et proches du centre n\u00e9vralgique de la ville.<\/p>\n<p>En ce temps, le Tunisia Palace, le Transatlantique, le Carlton, le Claridge, le M\u00e9tropole et le Majestic faisaient office de grands h\u00f4tels et leurs clients d&rsquo;hivernage contribuaient \u00e0 l&rsquo;animation de la ville.<\/p>\n<p>Ces taxis align\u00e9s t\u00e9moignent d&rsquo;une autre \u00e9poque, d&rsquo;autres automobiles et d&rsquo;un rythme de vie qui n&rsquo;est plus qu&rsquo;un souvenir.<\/p>\n<p>Aujourd&rsquo;hui, nos vies sont tr\u00e9pidantes et la vitesse s&rsquo;est empar\u00e9e de nous tous. Au point o\u00f9 il se d\u00e9gage de ce clich\u00e9 une certaine s\u00e9r\u00e9nit\u00e9.<\/p>\n<p>En ce temps, cochers et taxis se recrutaient parmi les Maltais de Tunis et si ces voitures pouvaient causer, elles auraient certainement mille et une histoires dans leur sac.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une photo unique : Taxis d&rsquo;antan \u00e0 la queue leu leu sur l&rsquo;avenue<\/p>\n","protected":false},"author":3229,"featured_media":376651,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2596],"tags":[],"class_list":["post-188266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Une photo unique : Taxis d&#039;antan \u00e0 la queue leu leu sur l&#039;avenue<\/title>\n<meta name=\"description\" content=\"Une photo unique : Taxis d&#039;antan \u00e0 la queue leu leu sur l&#039;avenue\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une photo unique : Taxis d&#039;antan \u00e0 la queue leu leu sur l&#039;avenue\" \/>\n<meta property=\"og:description\" content=\"Une photo unique : Taxis d&#039;antan \u00e0 la queue leu leu sur l&#039;avenue\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/hatem.bourial.2025\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-27T10:17:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2019\/06\/65394852_421148638480016_1169032107322769408_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"343\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hatem Bourial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hatem Bourial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/\"},\"author\":{\"name\":\"Hatem Bourial\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\"},\"headline\":\"Une photo unique : Taxis d&rsquo;antan \u00e0 la queue leu leu sur l&rsquo;avenue\",\"datePublished\":\"2019-06-27T10:17:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/\"},\"wordCount\":296,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/65394852_421148638480016_1169032107322769408_n.jpg\",\"articleSection\":[\"Chroniques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/\",\"name\":\"Une photo unique : Taxis d'antan \u00e0 la queue leu leu sur l'avenue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/65394852_421148638480016_1169032107322769408_n.jpg\",\"datePublished\":\"2019-06-27T10:17:00+00:00\",\"description\":\"Une photo unique : Taxis d'antan \u00e0 la queue leu leu sur l'avenue\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/65394852_421148638480016_1169032107322769408_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/65394852_421148638480016_1169032107322769408_n.jpg\",\"width\":500,\"height\":343,\"caption\":\"Une photo unique : Taxis d'antan \u00e0 la queue leu leu sur l'avenue\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/chroniques\\\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\\\/188266\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une photo unique : Taxis d&rsquo;antan \u00e0 la queue leu leu sur l&rsquo;avenue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/6bc0beba2cd23aec27cb5df85ca2554f\",\"name\":\"Hatem Bourial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/hatem-bourial_avatar-96x96.jpg\",\"caption\":\"Hatem Bourial\"},\"description\":\"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hatem.bourial.2025\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Fichier:Hatem_Bourial.jpg\"],\"knowsAbout\":[\"Culture & patrimoine tunisien\",\"Chronique soci\u00e9tale\",\"Litt\u00e9rature & m\u00e9moire\",\"Cin\u00e9ma & critique culturelle\",\"Identit\u00e9 & mutations sociales\"],\"knowsLanguage\":[\"Arabe\",\"Fran\u00e7ais\",\"Anglais\",\"Italien\",\"Polonais\"],\"jobTitle\":\"Journaliste, \u00e9crivain et chroniqueur culturel\",\"worksFor\":\"Webdo\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/hatem-bourial-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Une photo unique : Taxis d'antan \u00e0 la queue leu leu sur l'avenue","description":"Une photo unique : Taxis d'antan \u00e0 la queue leu leu sur l'avenue","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/","og_locale":"fr_FR","og_type":"article","og_title":"Une photo unique : Taxis d'antan \u00e0 la queue leu leu sur l'avenue","og_description":"Une photo unique : Taxis d'antan \u00e0 la queue leu leu sur l'avenue","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_author":"https:\/\/www.facebook.com\/hatem.bourial.2025","article_published_time":"2019-06-27T10:17:00+00:00","og_image":[{"width":500,"height":343,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2019\/06\/65394852_421148638480016_1169032107322769408_n.jpg","type":"image\/jpeg"}],"author":"Hatem Bourial","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"Hatem Bourial","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/"},"author":{"name":"Hatem Bourial","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f"},"headline":"Une photo unique : Taxis d&rsquo;antan \u00e0 la queue leu leu sur l&rsquo;avenue","datePublished":"2019-06-27T10:17:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/"},"wordCount":296,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2019\/06\/65394852_421148638480016_1169032107322769408_n.jpg","articleSection":["Chroniques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/","name":"Une photo unique : Taxis d'antan \u00e0 la queue leu leu sur l'avenue","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2019\/06\/65394852_421148638480016_1169032107322769408_n.jpg","datePublished":"2019-06-27T10:17:00+00:00","description":"Une photo unique : Taxis d'antan \u00e0 la queue leu leu sur l'avenue","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2019\/06\/65394852_421148638480016_1169032107322769408_n.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2019\/06\/65394852_421148638480016_1169032107322769408_n.jpg","width":500,"height":343,"caption":"Une photo unique : Taxis d'antan \u00e0 la queue leu leu sur l'avenue"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/chroniques\/une-photo-unique-taxis-dantan-a-la-queue-leu-leu-sur-lavenue\/188266\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Une photo unique : Taxis d&rsquo;antan \u00e0 la queue leu leu sur l&rsquo;avenue"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/6bc0beba2cd23aec27cb5df85ca2554f","name":"Hatem Bourial","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2026\/04\/hatem-bourial_avatar-96x96.jpg","caption":"Hatem Bourial"},"description":"Hatem Bourial est journaliste, \u00e9crivain et chroniqueur tunisien. Actif depuis plusieurs d\u00e9cennies, il s\u2019est impos\u00e9 comme un observateur attentif de la soci\u00e9t\u00e9 tunisienne, m\u00ealant dans ses \u00e9crits m\u00e9moire, culture et analyse du quotidien. Auteur de nombreux ouvrages, il d\u00e9veloppe une \u0153uvre \u00e0 la crois\u00e9e du r\u00e9cit, de la po\u00e9sie et de l\u2019observation sociologique. Parall\u00e8lement \u00e0 ses contributions dans la presse, il intervient r\u00e9guli\u00e8rement \u00e0 la radio et dans des espaces culturels, o\u00f9 il explore les enjeux li\u00e9s au patrimoine, \u00e0 l\u2019identit\u00e9 et aux transformations du monde contemporain. \u00c0 travers ses chroniques, Hatem Bourial propose une lecture sensible et approfondie de l\u2019actualit\u00e9, nourrie par une exp\u00e9rience journalistique et litt\u00e9raire reconnue. \ud83d\udd17 Facebook : https:\/\/www.facebook.com\/hatem.bourial.2025","sameAs":["https:\/\/www.facebook.com\/hatem.bourial.2025","https:\/\/fr.wikipedia.org\/wiki\/Fichier:Hatem_Bourial.jpg"],"knowsAbout":["Culture & patrimoine tunisien","Chronique soci\u00e9tale","Litt\u00e9rature & m\u00e9moire","Cin\u00e9ma & critique culturelle","Identit\u00e9 & mutations sociales"],"knowsLanguage":["Arabe","Fran\u00e7ais","Anglais","Italien","Polonais"],"jobTitle":"Journaliste, \u00e9crivain et chroniqueur culturel","worksFor":"Webdo","url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/hatem-bourial-2\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/188266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3229"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=188266"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/188266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/376651"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=188266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=188266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=188266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}