{"id":181522,"date":"2021-03-04T14:17:00","date_gmt":"2021-03-04T14:17:00","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/blog\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/"},"modified":"2025-05-15T09:01:24","modified_gmt":"2025-05-15T09:01:24","slug":"apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/","title":{"rendered":"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe"},"content":{"rendered":"<p>L\u2019Organisation mondiale de la Sant\u00e9 (OMS) a tir\u00e9 la sonnette d&rsquo;alarme, ce jeudi 4 mars 2021, concernant une augmentation du nombre de nouveaux cas de Covid-19 en Europe apr\u00e8s six semaines de baisse.<\/p>\n<p>La direction r\u00e9gionale de l&rsquo;OMS a, en effet, constat\u00e9 \u00ab\u00a0une r\u00e9surgence en Europe centrale et orientale et une augmentation des nouveaux cas dans plusieurs pays d\u2019Europe occidentale o\u00f9 les taux \u00e9taient d\u00e9j\u00e0 \u00e9lev\u00e9s\u00a0\u00bb.<\/p>\n<p>La semaine derni\u00e8re, les nouveaux cas de Covid-19 en Europe ont augment\u00e9 de 9% pour atteindre un peu plus d\u2019un million. La direction r\u00e9gionale de l&rsquo;OMS pr\u00e9conise ainsi d&rsquo;acc\u00e9l\u00e9rer la vaccination sachant que sur l\u2019ensemble des 53 pays de la r\u00e9gion europ\u00e9enne de l\u2019OMS, 8 n&rsquo;ont pas encore entam\u00e9 leur campagne de vaccination.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe<\/p>\n","protected":false},"author":3222,"featured_media":259348,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2598],"tags":[],"class_list":["post-181522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-international"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-04T14:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T09:01:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2021\/03\/coronavirus-reuters.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webdo.tn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webdo.tn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/\"},\"author\":{\"name\":\"webdo.tn\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/9a9c6118d687c117df8ef3cc36a4d175\"},\"headline\":\"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe\",\"datePublished\":\"2021-03-04T14:17:00+00:00\",\"dateModified\":\"2025-05-15T09:01:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/\"},\"wordCount\":155,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/coronavirus-reuters.jpg\",\"articleSection\":[\"International\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/\",\"name\":\"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/coronavirus-reuters.jpg\",\"datePublished\":\"2021-03-04T14:17:00+00:00\",\"dateModified\":\"2025-05-15T09:01:24+00:00\",\"description\":\"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/coronavirus-reuters.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/coronavirus-reuters.jpg\",\"width\":800,\"height\":450,\"caption\":\"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/international\\\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\\\/181522\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/9a9c6118d687c117df8ef3cc36a4d175\",\"name\":\"webdo.tn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"caption\":\"webdo.tn\"},\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/webdotn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe","description":"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/","og_locale":"fr_FR","og_type":"article","og_title":"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe","og_description":"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_published_time":"2021-03-04T14:17:00+00:00","article_modified_time":"2025-05-15T09:01:24+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2021\/03\/coronavirus-reuters.jpg","type":"image\/jpeg"}],"author":"webdo.tn","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"webdo.tn","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/"},"author":{"name":"webdo.tn","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/9a9c6118d687c117df8ef3cc36a4d175"},"headline":"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe","datePublished":"2021-03-04T14:17:00+00:00","dateModified":"2025-05-15T09:01:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/"},"wordCount":155,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2021\/03\/coronavirus-reuters.jpg","articleSection":["International"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/","name":"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2021\/03\/coronavirus-reuters.jpg","datePublished":"2021-03-04T14:17:00+00:00","dateModified":"2025-05-15T09:01:24+00:00","description":"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2021\/03\/coronavirus-reuters.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2021\/03\/coronavirus-reuters.jpg","width":800,"height":450,"caption":"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/international\/apres-six-semaines-de-baisse-loms-alerte-sur-une-hausse-des-nouveaux-cas-de-covid-19-en-europe\/181522\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Apr\u00e8s six semaines de baisse, l\u2019OMS alerte sur une hausse des nouveaux cas de Covid-19 en Europe"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/9a9c6118d687c117df8ef3cc36a4d175","name":"webdo.tn","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","caption":"webdo.tn"},"url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/webdotn\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/181522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3222"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=181522"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/181522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/259348"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=181522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=181522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=181522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}