{"id":170036,"date":"2014-01-15T19:35:00","date_gmt":"2014-01-15T19:35:00","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/actualite\/blog\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/"},"modified":"2025-06-04T18:35:13","modified_gmt":"2025-06-04T18:35:13","slug":"greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/","title":{"rendered":"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb"},"content":{"rendered":"<p>C\u2019est ce que vient d\u2019annoncer Naceur Selmi, Secr\u00e9taire G\u00e9n\u00e9ral du Syndicat des agents municipaux. Invit\u00e9 de l\u2019\u00e9mission \u00ab \u00e0 la page \u00bb sur Mosa\u00efque FM, Naceur Selmi a confirm\u00e9 le caract\u00e8re sauvage de la gr\u00e8ve des agents de propret\u00e9 de la ville de Tunis ce qui repr\u00e9sente en soi une ill\u00e9galit\u00e9. Il a confirm\u00e9, \u00e9galement, les menaces et pressions de quelques agents \u00e0 l\u2019encontre de leurs coll\u00e8gues pour les emp\u00eacher de reprendre le travail. Ces derniers, au nombre de 6, ont fait, aujourd\u2019hui, usage d\u2019armes blanches pour ne pas permettre la reprise du travail par la majorit\u00e9 des autres agents. Ils se sont fait assister par des personnes \u00e9trang\u00e8res \u00e0 la municipalit\u00e9 pour imposer leur volont\u00e9. Le responsable syndicaliste appelle les autorit\u00e9s \u00e0 d\u00e9clencher une enqu\u00eate pour identifier les fauteurs et leur faire assumer leur responsabilit\u00e9.Malgr\u00e9 son attitude sur le caract\u00e8re de la gr\u00e8ve et les incidents qui l\u2019ont accompagn\u00e9e, Naceur Selimi ne nie pas la l\u00e9gitimit\u00e9 des revendications des agents municipaux qui r\u00e9clament la majoration de l\u2019indemnit\u00e9 d\u2019hygi\u00e8ne et l\u2019instauration d\u2019un syst\u00e8me d\u2019avancement . Il a pr\u00e9cis\u00e9 que le traitement mensuel servi aux agents varie entre 350 et 400 dinars contre 200 \u00e0 250 dinars avant la r\u00e9volution .<\/p>\n<p>Il a conclu que les pourparlers avec les autorit\u00e9s se poursuivent et qu\u2019il est envisag\u00e9 la reprise du travail \u00e0 partir de demain sauf emp\u00eachement majeur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb<\/p>\n","protected":false},"author":3222,"featured_media":353429,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-170036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-national"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb<\/title>\n<meta name=\"description\" content=\"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb\" \/>\n<meta property=\"og:description\" content=\"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-15T19:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T18:35:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Poubelles-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"409\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webdo.tn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webdo.tn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/\"},\"author\":{\"name\":\"webdo.tn\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/9a9c6118d687c117df8ef3cc36a4d175\"},\"headline\":\"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb\",\"datePublished\":\"2014-01-15T19:35:00+00:00\",\"dateModified\":\"2025-06-04T18:35:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/\"},\"wordCount\":268,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/Poubelles-2-1.jpg\",\"articleSection\":[\"National\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/\",\"name\":\"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/Poubelles-2-1.jpg\",\"datePublished\":\"2014-01-15T19:35:00+00:00\",\"dateModified\":\"2025-06-04T18:35:13+00:00\",\"description\":\"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/Poubelles-2-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/Poubelles-2-1.jpg\",\"width\":600,\"height\":409,\"caption\":\"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\\\/170036\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/9a9c6118d687c117df8ef3cc36a4d175\",\"name\":\"webdo.tn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"caption\":\"webdo.tn\"},\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/webdotn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb","description":"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/","og_locale":"fr_FR","og_type":"article","og_title":"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb","og_description":"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_published_time":"2014-01-15T19:35:00+00:00","article_modified_time":"2025-06-04T18:35:13+00:00","og_image":[{"width":600,"height":409,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Poubelles-2-1.jpg","type":"image\/jpeg"}],"author":"webdo.tn","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"webdo.tn","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/"},"author":{"name":"webdo.tn","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/9a9c6118d687c117df8ef3cc36a4d175"},"headline":"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb","datePublished":"2014-01-15T19:35:00+00:00","dateModified":"2025-06-04T18:35:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/"},"wordCount":268,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Poubelles-2-1.jpg","articleSection":["National"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/","name":"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Poubelles-2-1.jpg","datePublished":"2014-01-15T19:35:00+00:00","dateModified":"2025-06-04T18:35:13+00:00","description":"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Poubelles-2-1.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Poubelles-2-1.jpg","width":600,"height":409,"caption":"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/greve-des-agents-municipaux-menaces-et-usage-darmes-blanches-pour-empecher-la-reprise-du-travail\/170036\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Gr\u00e8ve des agents municipaux : \u00ab Menaces et usage d\u2019armes blanches pour emp\u00eacher la reprise du travail \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/9a9c6118d687c117df8ef3cc36a4d175","name":"webdo.tn","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","caption":"webdo.tn"},"url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/webdotn\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/170036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3222"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=170036"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/170036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/353429"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=170036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=170036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=170036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}