{"id":170022,"date":"2014-01-17T15:06:00","date_gmt":"2014-01-17T15:06:00","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/actualite\/blog\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/"},"modified":"2025-06-04T18:34:47","modified_gmt":"2025-06-04T18:34:47","slug":"des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/","title":{"rendered":"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir"},"content":{"rendered":"<p>La r\u00e9cente apparition, sur les plateaux d\u2019une cha\u00eene TV, du G\u00e9n\u00e9ral Ahmed Chabir, ex-Directeur g\u00e9n\u00e9ral de la S\u00fbret\u00e9 militaire, puis au minist\u00e8re de l\u2019Int\u00e9rieur, n\u2019a pas cess\u00e9 d\u2019alimenter les discussions et susciter diff\u00e9rents commentaires, sinon cr\u00e9er une v\u00e9ritable pol\u00e9mique.<\/p>\n<p>Au-del\u00e0, d\u2019ailleurs, de la r\u00e9action de l\u2019ancien chef major des trois Arm\u00e9es, Rachid Ammar, voil\u00e0 que bon nombre d\u2019avocats, notamment repr\u00e9sentant la partie civile des martyrs de la R\u00e9volution, montent \u00e9galement au cr\u00e9neau, pour d\u00e9noncer les d\u00e9clarations et autres r\u00e9v\u00e9lations du G\u00e9n\u00e9ral Ahmed Chabir, allant jusqu\u2019\u00e0 l\u2019accuser de trahison, du moins de faux t\u00e9moignages, pour avoir fait allusion \u00e0 une intervention d\u2019une partie \u00e9trang\u00e8re.<\/p>\n<p>Ces d\u00e9fenseurs des int\u00e9r\u00eats des familles des martyrs sont d\u00e9termin\u00e9s \u00e0 aller plus loin encore en annon\u00e7ant leur intention d\u2019intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Chabir pour d\u00e9clarations calomnieuses, rapporte le quotidien Achourouk.<\/p>\n<p>Mieux, Me Charfeddine Elkalil, du groupe des 25, n\u2019a pas cach\u00e9 l\u2019indignation du groupe qui soup\u00e7onne une manipulation et une man\u0153uvre dont la finalit\u00e9 est de brouiller les pistes, sinon perturber la marche normale des affaires confi\u00e9es \u00e0 la Magistrature militaire\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir<\/p>\n","protected":false},"author":3222,"featured_media":353435,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-170022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-national"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir<\/title>\n<meta name=\"description\" content=\"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir\" \/>\n<meta property=\"og:description\" content=\"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-17T15:06:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T18:34:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Ahmed-Chabir.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"228\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webdo.tn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webdo.tn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/\"},\"author\":{\"name\":\"webdo.tn\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/9a9c6118d687c117df8ef3cc36a4d175\"},\"headline\":\"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir\",\"datePublished\":\"2014-01-17T15:06:00+00:00\",\"dateModified\":\"2025-06-04T18:34:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/\"},\"wordCount\":246,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/Ahmed-Chabir.jpg\",\"articleSection\":[\"National\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/\",\"name\":\"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/Ahmed-Chabir.jpg\",\"datePublished\":\"2014-01-17T15:06:00+00:00\",\"dateModified\":\"2025-06-04T18:34:47+00:00\",\"description\":\"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/Ahmed-Chabir.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/Ahmed-Chabir.jpg\",\"width\":228,\"height\":200,\"caption\":\"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\\\/170022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/9a9c6118d687c117df8ef3cc36a4d175\",\"name\":\"webdo.tn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"caption\":\"webdo.tn\"},\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/webdotn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir","description":"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/","og_locale":"fr_FR","og_type":"article","og_title":"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir","og_description":"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_published_time":"2014-01-17T15:06:00+00:00","article_modified_time":"2025-06-04T18:34:47+00:00","og_image":[{"width":228,"height":200,"url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Ahmed-Chabir.jpg","type":"image\/jpeg"}],"author":"webdo.tn","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"webdo.tn","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/"},"author":{"name":"webdo.tn","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/9a9c6118d687c117df8ef3cc36a4d175"},"headline":"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir","datePublished":"2014-01-17T15:06:00+00:00","dateModified":"2025-06-04T18:34:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/"},"wordCount":246,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Ahmed-Chabir.jpg","articleSection":["National"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/","name":"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Ahmed-Chabir.jpg","datePublished":"2014-01-17T15:06:00+00:00","dateModified":"2025-06-04T18:34:47+00:00","description":"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Ahmed-Chabir.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2014\/01\/Ahmed-Chabir.jpg","width":228,"height":200,"caption":"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/des-avocats-dont-le-groupe-des-25-decides-intenter-proces-lencontre-du-general-ahmed-chabir\/170022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"Des avocats, dont le groupe des 25, d\u00e9cid\u00e9s \u00e0 intenter un proc\u00e8s \u00e0 l\u2019encontre du G\u00e9n\u00e9ral Ahmed Chabir"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/9a9c6118d687c117df8ef3cc36a4d175","name":"webdo.tn","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","caption":"webdo.tn"},"url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/webdotn\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/170022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3222"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=170022"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/170022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/353435"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=170022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=170022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=170022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}