{"id":169968,"date":"2014-01-26T20:21:00","date_gmt":"2014-01-26T20:21:00","guid":{"rendered":"https:\/\/www.webdo.tn\/fr\/actualite\/blog\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/"},"modified":"2025-05-22T13:16:05","modified_gmt":"2025-05-22T13:16:05","slug":"lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa","status":"publish","type":"post","link":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/","title":{"rendered":"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa"},"content":{"rendered":"<p>Suite aux contestations suscit\u00e9es par l\u2019amendement de l\u2019article 19 de la loi constitutionnelle relative \u00e0 l\u2019organisation provisoire des pouvoirs, op\u00e9r\u00e9 lors de la s\u00e9ance pl\u00e9ni\u00e8re de la veille, la question a \u00e9t\u00e9 soulev\u00e9e \u00e0 nouveau dans le cadre d\u2019une r\u00e9union de l\u2019assembl\u00e9e pour revoir cet amendement, jug\u00e9 incompatible avec les r\u00e9solutions de la feuille de route. <\/p>\n<p>Pr\u00e9alablement \u00e0 la tenue de cette assembl\u00e9e, les pr\u00e9sidents de blocs parlementaires et leurs repr\u00e9sentants se sont r\u00e9unis cette apr\u00e8s-midi pour proposer une version conforme aux recommandations du dialogue national. Leur proposition ne s\u2019est pas limit\u00e9e \u00e0 revoir les dispositions de l\u2019article 19 du r\u00e8glement int\u00e9rieur. Elle s\u2019est \u00e9tendue \u00e0 l\u2019article 4 de la loi susvis\u00e9e en lui ajoutant des dispositions relatives \u00e0 l\u2019autonomie financi\u00e8re et administrative de l\u2019Assembl\u00e9e. <\/p>\n<p>Mise en d\u00e9bat au cours de la s\u00e9ance de ce soir, la proposition dans son ensemble a \u00e9t\u00e9 vot\u00e9e \u00e0 148 voix contre 23 abstentions et 34 votes n\u00e9gatifs.<\/p>\n<p>En vertu des r\u00e9sultats de ce vote, le retrait de la confiance du gouvernement et des ministres d\u00e9pend du vote d\u2019une motion de censure \u00e0 la majorit\u00e9 des 3\/5\u00e8me alors que selon l\u2019amendement d\u2019hier, les ministres \u00e9taient r\u00e9vocables \u00e0 plus de 50% des voix. En outre, l\u2019amendement pr\u00e9voit l\u2019attribution d\u2019une autonomie financi\u00e8re et administrative \u00e0 l\u2019assembl\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa<\/p>\n","protected":false},"author":3222,"featured_media":374888,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-169968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-national"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa<\/title>\n<meta name=\"description\" content=\"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa\" \/>\n<meta property=\"og:description\" content=\"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/\" \/>\n<meta property=\"og:site_name\" content=\"webdo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/webdotn\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-26T20:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-22T13:16:05+00:00\" \/>\n<meta name=\"author\" content=\"webdo.tn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:site\" content=\"@webdo_tn\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webdo.tn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/\"},\"author\":{\"name\":\"webdo.tn\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/9a9c6118d687c117df8ef3cc36a4d175\"},\"headline\":\"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa\",\"datePublished\":\"2014-01-26T20:21:00+00:00\",\"dateModified\":\"2025-05-22T13:16:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/\"},\"wordCount\":256,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Assemblee-Nationale-Constituante-photo-le-journalcom_169968.jpg\",\"articleSection\":[\"National\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/\",\"name\":\"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Assemblee-Nationale-Constituante-photo-le-journalcom_169968.jpg\",\"datePublished\":\"2014-01-26T20:21:00+00:00\",\"dateModified\":\"2025-05-22T13:16:05+00:00\",\"description\":\"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Assemblee-Nationale-Constituante-photo-le-journalcom_169968.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Assemblee-Nationale-Constituante-photo-le-journalcom_169968.jpg\",\"width\":300,\"height\":200,\"caption\":\"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/national\\\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\\\/169968\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"name\":\"webdo\",\"description\":\"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#organization\",\"name\":\"Webdo\",\"alternateName\":\"Webdo.tn\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"contentUrl\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Webdo-Tunisie_168377.jpg\",\"width\":301,\"height\":301,\"caption\":\"Webdo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/webdotn\",\"https:\\\/\\\/x.com\\\/webdo_tn\"],\"description\":\"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.\",\"email\":\"redac@webdo.tn\",\"legalName\":\"YNJ SARL\",\"foundingDate\":\"2010-09-06\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/#\\\/schema\\\/person\\\/9a9c6118d687c117df8ef3cc36a4d175\",\"name\":\"webdo.tn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g\",\"caption\":\"webdo.tn\"},\"url\":\"https:\\\/\\\/www.webdo.tn\\\/fr\\\/actualite\\\/author\\\/webdotn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa","description":"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa","canonical":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa","og_description":"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa","og_url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/","og_site_name":"webdo","article_publisher":"https:\/\/www.facebook.com\/webdotn","article_published_time":"2014-01-26T20:21:00+00:00","article_modified_time":"2025-05-22T13:16:05+00:00","author":"webdo.tn","twitter_card":"summary_large_image","twitter_creator":"@webdo_tn","twitter_site":"@webdo_tn","twitter_misc":{"\u00c9crit par":"webdo.tn","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/#article","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/"},"author":{"name":"webdo.tn","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/9a9c6118d687c117df8ef3cc36a4d175"},"headline":"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa","datePublished":"2014-01-26T20:21:00+00:00","dateModified":"2025-05-22T13:16:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/"},"wordCount":256,"commentCount":0,"publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Assemblee-Nationale-Constituante-photo-le-journalcom_169968.jpg","articleSection":["National"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/","url":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/","name":"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa","isPartOf":{"@id":"https:\/\/www.webdo.tn\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/#primaryimage"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/#primaryimage"},"thumbnailUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Assemblee-Nationale-Constituante-photo-le-journalcom_169968.jpg","datePublished":"2014-01-26T20:21:00+00:00","dateModified":"2025-05-22T13:16:05+00:00","description":"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa","breadcrumb":{"@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/#primaryimage","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Assemblee-Nationale-Constituante-photo-le-journalcom_169968.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Assemblee-Nationale-Constituante-photo-le-journalcom_169968.jpg","width":300,"height":200,"caption":"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.webdo.tn\/fr\/actualite\/national\/lanc-revient-sur-les-amendements-en-attendant-lannonce-du-gouvernement-de-jomaa\/169968\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.webdo.tn\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019ANC revient sur les amendements en attendant l\u2019annonce du gouvernement de Jomaa"}]},{"@type":"WebSite","@id":"https:\/\/www.webdo.tn\/fr\/#website","url":"https:\/\/www.webdo.tn\/fr\/","name":"webdo","description":"Tunisie - News en Tunisie et \u00e0 l&#039;international sur Webdo.tn","publisher":{"@id":"https:\/\/www.webdo.tn\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.webdo.tn\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.webdo.tn\/fr\/#organization","name":"Webdo","alternateName":"Webdo.tn","url":"https:\/\/www.webdo.tn\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","contentUrl":"https:\/\/www.webdo.tn\/fr\/wp-content\/uploads\/2025\/06\/Webdo-Tunisie_168377.jpg","width":301,"height":301,"caption":"Webdo"},"image":{"@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/webdotn","https:\/\/x.com\/webdo_tn"],"description":"Webdo est un m\u00e9dia num\u00e9rique tunisien fond\u00e9 en 2010, sp\u00e9cialis\u00e9 dans l\u2019actualit\u00e9 nationale et internationale, l\u2019\u00e9conomie, la soci\u00e9t\u00e9 et les analyses politiques. Le site s\u2019adresse \u00e0 un large public francophone et couvre l\u2019information tunisienne en temps r\u00e9el.","email":"redac@webdo.tn","legalName":"YNJ SARL","foundingDate":"2010-09-06","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}},{"@type":"Person","@id":"https:\/\/www.webdo.tn\/fr\/#\/schema\/person\/9a9c6118d687c117df8ef3cc36a4d175","name":"webdo.tn","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ce1f28c0c3bbac99ff550b85ef8e44a6950c6ee24514fb6a5489e51d06f0298?s=96&d=mm&r=g","caption":"webdo.tn"},"url":"https:\/\/www.webdo.tn\/fr\/actualite\/author\/webdotn\/"}]}},"_links":{"self":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/169968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/users\/3222"}],"replies":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/comments?post=169968"}],"version-history":[{"count":0,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/posts\/169968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media\/374888"}],"wp:attachment":[{"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/media?parent=169968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/categories?post=169968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.webdo.tn\/fr\/wp-json\/wp\/v2\/tags?post=169968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}